{"id":10209,"date":"2022-04-27T13:38:10","date_gmt":"2022-04-27T13:38:10","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=10209"},"modified":"2022-05-10T13:42:59","modified_gmt":"2022-05-10T13:42:59","slug":"assistere-una-persona-nellalimentazione","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/","title":{"rendered":"Assistere una persona nell&#8217;alimentazione"},"content":{"rendered":"<p>L\u2019assistenza \u00e8 una delle professioni pi\u00f9 appaganti a livello etico e morale, perch\u00e9 ci si impegna ad aiutare il prossimo in un\u2019azione che, a cause di forze maggiori, non \u00e8 in grado di svolgere da solo. Ad esempio, l\u2019<strong>assistenza alla persona nell\u2019alimentazione<\/strong>\u00a0\u00e8 una mansione estremamente importante, perch\u00e9 si fornisce supporto a chi non \u00e8 in grado di mangiare autonomamente.<\/p>\n<h2><strong>Chi svolge questo mestiere?<\/strong><\/h2>\n<p>La figura che si occupa di questo mestiere \u00e8\u00a0l\u2019<strong>assistente alla persona<\/strong>, uno specialista di supporto ai ruoli sanitari . Il compito di questi assistenti \u00e8 quello di dare una mano a tutte quelle persone che non riescono a gestirsi da soli o che necessitano di un controllo costante durante la loro quotidianit\u00e0.<\/p>\n<p><a href=\"https:\/\/www.emagister.it\/corsi_corsicef_centro_europeo_di_formazione-cen-58031.htm\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-9560 size-full\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/01\/m-16.png\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/p>\n<h2><strong>Cosa deve verificare l&#8217;assistente?<\/strong><\/h2>\n<p>La prima cosa da fare\u00a0<strong>\u00e8 preparare un piano assistenziale al paziente<\/strong>. La programmazione \u00e8 unica per ogni persona, dato che occorre assolutamente verificare di quale aiuto necessita, ma soprattutto perch\u00e9 esistono patologie diverse per ognuno.<\/p>\n<p>Per prima cosa, l\u2019assistente alla persona deve verificare che la dieta affidata al paziente sia quella corretta. Come altro processo di verifica, la figura preposta dovr\u00e0 prescrivere determinate diete o digiuni qualora il paziente dovesse affrontare controlli o analisi che lo richiedono.<\/p>\n<h2>Interventi che deve attuare<\/h2>\n<p>Oltre alle verifiche esaminate nel paragrafo precedente, l\u2019<strong>assistente alla persona<\/strong>\u00a0deve attuare importanti interventi per quel che concerne\u00a0<strong>la preparazione all\u2019alimentazione<\/strong>, come:<\/p>\n<ul>\n<li>preparare i pasti;<\/li>\n<li>fornire supporto al paziente;<\/li>\n<li>garantire al paziente tutto l\u2019occorrente per mangiare;<\/li>\n<li>imboccare il paziente, se presenta importanti deficit fisici.<\/li>\n<\/ul>\n<h2><strong>Quali altre azioni deve svolgere?<\/strong><\/h2>\n<p>Sempre per quello che riguarda l\u2019<strong>assistenza alla persona nell\u2019alimentazione<\/strong>, l\u2019incaricato dovr\u00e0 far s\u00ec che l\u2019igiene del paziente sia sempre ottimale, quindi occorrer\u00e0 affiancarlo nella pulizia personale.<\/p>\n<p>La\u00a0<strong>pulizia dell\u2019ambiente<\/strong>\u00a0\u00e8 altamente importante, soprattutto perch\u00e9 sono spazi in cui i pazienti si troveranno a condividere al momento dei pasti.<\/p>\n<p>A fine pasto, l\u2019assistente alla persona deve riferire all\u2019infermiere\u00a0<strong>un resoconto del pasto<\/strong>: se il paziente ha mangiato tutto, una parte o nulla, se ha ingerito liquidi; se ha avuto difficolt\u00e0 nella fase di assimilazione, oppure se ha avuto comportamenti non consoni e se si \u00e8 sentito male fisicamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019assistenza \u00e8 una delle professioni pi\u00f9 appaganti a livello etico e morale, perch\u00e9 ci si impegna ad aiutare il prossimo in un\u2019azione che, a cause di forze maggiori, non \u00e8 in grado di svolgere da solo. Ad esempio, l\u2019assistenza alla persona nell\u2019alimentazione\u00a0\u00e8 una mansione estremamente importante, perch\u00e9 si fornisce supporto a chi non \u00e8 in [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":10210,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[260,592,867,923,924,1085],"class_list":["post-10209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-clienti","tag-centri-di-formazione","tag-centri-emagister","tag-noticiasskuola","tag-923","tag-centro-europeo-di-formazione-cef","tag-ij_sector_center_50659050082349536565505351654569_137"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assistere una persona nell&#039;alimentazione - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assistere una persona nell&#039;alimentazione - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"L\u2019assistenza \u00e8 una delle professioni pi\u00f9 appaganti a livello etico e morale, perch\u00e9 ci si impegna ad aiutare il prossimo in un\u2019azione che, a cause di forze maggiori, non \u00e8 in grado di svolgere da solo. Ad esempio, l\u2019assistenza alla persona nell\u2019alimentazione\u00a0\u00e8 una mansione estremamente importante, perch\u00e9 si fornisce supporto a chi non \u00e8 in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-27T13:38:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-10T13:42:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/05\/GettyImages-1329785855.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/assistere-una-persona-nellalimentazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/assistere-una-persona-nellalimentazione\\\/\"},\"author\":{\"name\":\"Redazione Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\"},\"headline\":\"Assistere una persona nell&#8217;alimentazione\",\"datePublished\":\"2022-04-27T13:38:10+00:00\",\"dateModified\":\"2022-05-10T13:42:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/assistere-una-persona-nellalimentazione\\\/\"},\"wordCount\":360,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/assistere-una-persona-nellalimentazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/GettyImages-1329785855.jpg\",\"keywords\":[\"Centri di Formazione\",\"centri emagister\",\"noticiasSkuola\",\"50659050082349536565505351654569\",\"Centro Europeo di Formazione - CEF\",\"ij_sector_center_50659050082349536565505351654569_137\"],\"articleSection\":[\"I Nostri Clienti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/assistere-una-persona-nellalimentazione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/assistere-una-persona-nellalimentazione\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/assistere-una-persona-nellalimentazione\\\/\",\"name\":\"Assistere una persona nell'alimentazione - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/assistere-una-persona-nellalimentazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/assistere-una-persona-nellalimentazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/GettyImages-1329785855.jpg\",\"datePublished\":\"2022-04-27T13:38:10+00:00\",\"dateModified\":\"2022-05-10T13:42:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/assistere-una-persona-nellalimentazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/assistere-una-persona-nellalimentazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/assistere-una-persona-nellalimentazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/GettyImages-1329785855.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/GettyImages-1329785855.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/assistere-una-persona-nellalimentazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Nostri Clienti\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/i-nostri-clienti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Assistere una persona nell&#8217;alimentazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\",\"name\":\"Redazione Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Redazione Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/redazione-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assistere una persona nell'alimentazione - Emagister Blog Italia","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Assistere una persona nell'alimentazione - Emagister Blog Italia","og_description":"L\u2019assistenza \u00e8 una delle professioni pi\u00f9 appaganti a livello etico e morale, perch\u00e9 ci si impegna ad aiutare il prossimo in un\u2019azione che, a cause di forze maggiori, non \u00e8 in grado di svolgere da solo. Ad esempio, l\u2019assistenza alla persona nell\u2019alimentazione\u00a0\u00e8 una mansione estremamente importante, perch\u00e9 si fornisce supporto a chi non \u00e8 in [&hellip;]","og_url":"https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2022-04-27T13:38:10+00:00","article_modified_time":"2022-05-10T13:42:59+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/05\/GettyImages-1329785855.jpg","type":"image\/jpeg"}],"author":"Redazione Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Redazione Emagister","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/"},"author":{"name":"Redazione Emagister","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897"},"headline":"Assistere una persona nell&#8217;alimentazione","datePublished":"2022-04-27T13:38:10+00:00","dateModified":"2022-05-10T13:42:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/"},"wordCount":360,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/05\/GettyImages-1329785855.jpg","keywords":["Centri di Formazione","centri emagister","noticiasSkuola","50659050082349536565505351654569","Centro Europeo di Formazione - CEF","ij_sector_center_50659050082349536565505351654569_137"],"articleSection":["I Nostri Clienti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/","url":"https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/","name":"Assistere una persona nell'alimentazione - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/05\/GettyImages-1329785855.jpg","datePublished":"2022-04-27T13:38:10+00:00","dateModified":"2022-05-10T13:42:59+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/05\/GettyImages-1329785855.jpg","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/05\/GettyImages-1329785855.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/assistere-una-persona-nellalimentazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"I Nostri Clienti","item":"https:\/\/www.emagister.it\/blog\/category\/i-nostri-clienti\/"},{"@type":"ListItem","position":3,"name":"Assistere una persona nell&#8217;alimentazione"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897","name":"Redazione Emagister","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Redazione Emagister"},"url":"https:\/\/www.emagister.it\/blog\/author\/redazione-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/10209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=10209"}],"version-history":[{"count":2,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/10209\/revisions"}],"predecessor-version":[{"id":10212,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/10209\/revisions\/10212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/10210"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=10209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=10209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=10209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}