{"id":10580,"date":"2022-09-30T09:42:49","date_gmt":"2022-09-30T09:42:49","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=10580"},"modified":"2022-09-30T09:42:49","modified_gmt":"2022-09-30T09:42:49","slug":"in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/","title":{"rendered":"In vigore il nuovo Codice della Crisi d\u2019impresa: responsabilit\u00e0 e strumenti di tutela per amministratori e imprenditori"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Dal <\/span><b>15 luglio 2022<\/b><span style=\"font-weight: 400;\"> \u00e8 in vigore il <\/span><b>d.lgs. 83\/22<\/b><span style=\"font-weight: 400;\"> che ha reso operativo il <\/span><b>nuovo Codice della Crisi d\u2019impresa e dell\u2019insolvenza<\/b><span style=\"font-weight: 400;\">. La normativa impone <\/span><b>nuovi obblighi<\/b><span style=\"font-weight: 400;\"> a tutti gli imprenditori e amministratori di aziende:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>istituire un assetto organizzativo, amministrativo e contabile adeguato<\/b><span style=\"font-weight: 400;\">, in base al contesto aziendale, per rilevare tempestivamente una possibile crisi;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>attuare uno degli strumenti previsti dall\u2019ordinamento<\/b><span style=\"font-weight: 400;\"> per garantire la continuit\u00e0 produttiva.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Si tratta di una vera e propria <\/span><b>rivoluzione<\/b><span style=\"font-weight: 400;\"> per quanto riguarda le <\/span><b>responsabilit\u00e0<\/b><span style=\"font-weight: 400;\"> e l\u2019<\/span><b>operato degli amministratori<\/b><span style=\"font-weight: 400;\">. Ora l\u2019imprenditore\/amministratore di un\u2019azienda deve <\/span><b>adottare precise misure<\/b><span style=\"font-weight: 400;\"> (se impresa individuale) <\/span><b>o adeguati assetti organizzativi, amministrativi e contabili<\/b><span style=\"font-weight: 400;\"> (se societ\u00e0), al fine di <\/span><b>rilevare tempestivamente situazioni di difficolt\u00e0<\/b><span style=\"font-weight: 400;\">, cos\u00ec da poter intervenire prima che sfocino in insolvenza irreversibile.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">In caso contrario rischia <\/span><b>pesanti sanzioni civili<\/b><span style=\"font-weight: 400;\"> (confisca o pignoramento di beni) <\/span><b>e penali<\/b><span style=\"font-weight: 400;\"> (detenzione fino a 10 anni per bancarotta).<\/span><\/p>\n<p><strong><span style=\"font-weight: 400;\"><b><a href=\"https:\/\/www.emagister.it\/corsi_professional_academy_aidem_srl-cen-105491.htm\" target=\"_blank\" rel=\"noopener noopenernofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-8036 size-full\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/05\/Professional-Accademy.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/b><\/span><\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Secondo l\u2019art. 3 del D.Lgs. 83\/22 l\u2019amministratore deve adottare misure idonee al fine di:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>rilevare squilibri<\/b><span style=\"font-weight: 400;\"> patrimoniali o economico-finanziari;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>verificare la non sostenibilit\u00e0 dei debiti<\/b><span style=\"font-weight: 400;\"> (verso il personale, i fornitori o le banche) <\/span><b>e l\u2019assenza di prospettive di continuit\u00e0<\/b><span style=\"font-weight: 400;\"> aziendale per i 12 mesi successivi;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">ricavare le informazioni necessarie a effettuare il test pratico per verificare la perseguibilit\u00e0 del risanamento.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">La normativa fornisce diversi <\/span><b>strumenti per il risanamento di una crisi<\/b><span style=\"font-weight: 400;\">. Una delle novit\u00e0 principali riguarda il <\/span><b>piano di ristrutturazione soggetto a omologazione<\/b><span style=\"font-weight: 400;\">. \u00c8 applicabile solo all\u2019imprenditore commerciale soggetto alla liquidazione giudiziale (non a imprese minori o agricole) e si avvicina al concordato preventivo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il principale cambiamento rispetto al passato riguarda il fatto che <\/span><b>il debitore pu\u00f2 soddisfare i creditori distribuendo il valore generato dal piano anche in deroga<\/b><span style=\"font-weight: 400;\"> a quanto stabilito dal Codice civile. Ha dunque una <\/span><b>discrezionalit\u00e0 assoluta<\/b><span style=\"font-weight: 400;\"> su come distribuire le risorse, senza dover rispondere dell\u2019adempimento delle obbligazioni con tutti i suoi beni presenti e futuri e pu\u00f2 non rispettare le norme di graduazione delle cause legittime di prelazione. Tutto ci\u00f2 <\/span><b>a condizione che la proposta sia approvata all\u2019unanimit\u00e0 da tutti i creditori<\/b><span style=\"font-weight: 400;\">. Restano fuori da questa possibilit\u00e0 i lavoratori: devono essere soddisfatti in denaro integralmente entro 30 giorni dall\u2019omologazione.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Per <\/span><b>aiutare gli imprenditori ad adeguare gli assetti aziendali e tutelarsi in caso di crisi<\/b><span style=\"font-weight: 400;\">, abbiamo organizzato il corso online di formazione pratica (e-Seminar) <\/span><b>\u201cStrumenti e Modelli per il monitoraggio e l\u2019adeguamento degli assetti per tutelare l\u2019amministratore dopo il nuovo Codice della Crisi d\u2019impresa e il D.Lgs. 83\/22\u201d<\/b><span style=\"font-weight: 400;\">. Il corso \u00e8 suddiviso in <\/span><b>4 lezioni<\/b><span style=\"font-weight: 400;\">, messe a disposizione a cadenza settimanale tramite una piattaforma web riservata.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Per consultare il programma e scaricare il modulo d\u2019iscrizione <\/span><b>clicchi qui<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 15 luglio 2022 \u00e8 in vigore il d.lgs. 83\/22 che ha reso operativo il nuovo Codice della Crisi d\u2019impresa e dell\u2019insolvenza. La normativa impone nuovi obblighi a tutti gli imprenditori e amministratori di aziende: istituire un assetto organizzativo, amministrativo e contabile adeguato, in base al contesto aziendale, per rilevare tempestivamente una possibile crisi; attuare [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":10582,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[1215,260,592,867,1138,1139],"class_list":["post-10580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-clienti","tag-ij_sector_center_99992269674249392522766775091915_24","tag-centri-di-formazione","tag-centri-emagister","tag-noticiasskuola","tag-1138","tag-professional-academy-aidem-srl"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>In vigore il nuovo Codice della Crisi d\u2019impresa: responsabilit\u00e0 e strumenti di tutela per amministratori e imprenditori - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In vigore il nuovo Codice della Crisi d\u2019impresa: responsabilit\u00e0 e strumenti di tutela per amministratori e imprenditori - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"Dal 15 luglio 2022 \u00e8 in vigore il d.lgs. 83\/22 che ha reso operativo il nuovo Codice della Crisi d\u2019impresa e dell\u2019insolvenza. La normativa impone nuovi obblighi a tutti gli imprenditori e amministratori di aziende: istituire un assetto organizzativo, amministrativo e contabile adeguato, in base al contesto aziendale, per rilevare tempestivamente una possibile crisi; attuare [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-30T09:42:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/09\/GettyImages-1335531271.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\\\/\"},\"author\":{\"name\":\"Redazione Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\"},\"headline\":\"In vigore il nuovo Codice della Crisi d\u2019impresa: responsabilit\u00e0 e strumenti di tutela per amministratori e imprenditori\",\"datePublished\":\"2022-09-30T09:42:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\\\/\"},\"wordCount\":447,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/GettyImages-1335531271.jpg\",\"keywords\":[\"ij_sector_center_99992269674249392522766775091915_24\",\"Centri di Formazione\",\"centri emagister\",\"noticiasSkuola\",\"99992269674249392522766775091915\",\"Professional Academy - Aidem srl\"],\"articleSection\":[\"I Nostri Clienti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\\\/\",\"name\":\"In vigore il nuovo Codice della Crisi d\u2019impresa: responsabilit\u00e0 e strumenti di tutela per amministratori e imprenditori - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/GettyImages-1335531271.jpg\",\"datePublished\":\"2022-09-30T09:42:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/GettyImages-1335531271.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/GettyImages-1335531271.jpg\",\"width\":1920,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Nostri Clienti\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/i-nostri-clienti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"In vigore il nuovo Codice della Crisi d\u2019impresa: responsabilit\u00e0 e strumenti di tutela per amministratori e imprenditori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\",\"name\":\"Redazione Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Redazione Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/redazione-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In vigore il nuovo Codice della Crisi d\u2019impresa: responsabilit\u00e0 e strumenti di tutela per amministratori e imprenditori - Emagister Blog Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/","og_locale":"it_IT","og_type":"article","og_title":"In vigore il nuovo Codice della Crisi d\u2019impresa: responsabilit\u00e0 e strumenti di tutela per amministratori e imprenditori - Emagister Blog Italia","og_description":"Dal 15 luglio 2022 \u00e8 in vigore il d.lgs. 83\/22 che ha reso operativo il nuovo Codice della Crisi d\u2019impresa e dell\u2019insolvenza. La normativa impone nuovi obblighi a tutti gli imprenditori e amministratori di aziende: istituire un assetto organizzativo, amministrativo e contabile adeguato, in base al contesto aziendale, per rilevare tempestivamente una possibile crisi; attuare [&hellip;]","og_url":"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2022-09-30T09:42:49+00:00","og_image":[{"width":1920,"height":900,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/09\/GettyImages-1335531271.jpg","type":"image\/jpeg"}],"author":"Redazione Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Redazione Emagister","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/"},"author":{"name":"Redazione Emagister","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897"},"headline":"In vigore il nuovo Codice della Crisi d\u2019impresa: responsabilit\u00e0 e strumenti di tutela per amministratori e imprenditori","datePublished":"2022-09-30T09:42:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/"},"wordCount":447,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/09\/GettyImages-1335531271.jpg","keywords":["ij_sector_center_99992269674249392522766775091915_24","Centri di Formazione","centri emagister","noticiasSkuola","99992269674249392522766775091915","Professional Academy - Aidem srl"],"articleSection":["I Nostri Clienti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/","url":"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/","name":"In vigore il nuovo Codice della Crisi d\u2019impresa: responsabilit\u00e0 e strumenti di tutela per amministratori e imprenditori - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/09\/GettyImages-1335531271.jpg","datePublished":"2022-09-30T09:42:49+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/09\/GettyImages-1335531271.jpg","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/09\/GettyImages-1335531271.jpg","width":1920,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/in-vigore-il-nuovo-codice-della-crisi-dimpresa-responsabilita-e-strumenti-di-tutela-per-amministratori-e-imprenditori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"I Nostri Clienti","item":"https:\/\/www.emagister.it\/blog\/category\/i-nostri-clienti\/"},{"@type":"ListItem","position":3,"name":"In vigore il nuovo Codice della Crisi d\u2019impresa: responsabilit\u00e0 e strumenti di tutela per amministratori e imprenditori"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897","name":"Redazione Emagister","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Redazione Emagister"},"url":"https:\/\/www.emagister.it\/blog\/author\/redazione-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/10580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=10580"}],"version-history":[{"count":2,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/10580\/revisions"}],"predecessor-version":[{"id":10769,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/10580\/revisions\/10769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/10582"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=10580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=10580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=10580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}