{"id":10591,"date":"2022-10-03T12:58:54","date_gmt":"2022-10-03T12:58:54","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=10591"},"modified":"2022-10-04T16:01:13","modified_gmt":"2022-10-04T16:01:13","slug":"8-settembre-giornata-mondiale-della-fisioterapia","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/","title":{"rendered":"8 settembre: Giornata Mondiale della Fisioterapia"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">La sedicesima edizione della <\/span><b>World Confederation for Physical Therapy<\/b><span style=\"font-weight: 400;\"> (WP \u2013 World Physiotherapy), che si tiene ogni 8 settembre, quest\u2019anno pone l\u2019accento su una patologia che si stima, affligga circa 520 milioni di persone in tutto il mondo: <\/span><b>l\u2019Osteoartrite<\/b><span style=\"font-weight: 400;\">, 11\u00b0 causa di disabilit\u00e0 a livello mondiale.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L\u2019Osteoartrite \u00e8 una malattia cronica che spesso \u00e8 associata a disfunzioni motorie che possono limitare temporaneamente o permanentemente le attivit\u00e0 di vita quotidiana.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il Fisioterapista, da sempre impegnato al contrasto ed alla prevenzione di malattie invalidanti, ha un ruolo sempre pi\u00f9 importante nell\u2019affermazione di modelli di cura e presa in carico del paziente affetto da malattie croniche. Attraverso gli esercizi terapeutici, il Fisioterapista aiuta a migliorare la capacit\u00e0 funzionale e la qualit\u00e0 della vita delle persone nei differenti contesti di vita.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.emagister.it\/corsi_unicamillus_international_medical_university-ef106220.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-6542\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2020\/07\/descarga-1-300x160.png\" alt=\"\" width=\"257\" height=\"137\" \/><\/a><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Per celebrare la Giornata mondiale della Fisioterapia sono state organizzate diverse iniziative ed <a href=\"https:\/\/www.emagister.it\/corsi_unicamillus_international_medical_university-ef106220.htm\"><strong>UniCamillus<\/strong><\/a> partecipa, con la collaborazione dei <\/span><b>tirocinanti del <a href=\"https:\/\/www.emagister.it\/corso_di_laurea_fisioterapia_erogato_inglese-ec2802646.htm\">Corso di Laurea in Fisioterapia<\/a><\/b><span style=\"font-weight: 400;\"> ad eventi di sensibilizzazione promossi dall\u2019<\/span><b>ASL Roma 3 <\/b><span style=\"font-weight: 400;\">e dall\u2019<\/span><b>ASL Roma 6<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">In occasione della giornata all\u2019ASL Roma 3 si \u00e8 parlato di <\/span><b><i>Riabilitazione al \u201ccentro\u201d tra storia e futuro<\/i><\/b><span style=\"font-weight: 400;\"> mentre presso la sede del Senato della Repubblica di Palazzo Giustiniani si \u00e8 tenuto il convegno <\/span><b><i>PNRR e DM 77. Artrosi e malattie reumatiche nei nuovi modelli di assistenza territoriale: il contributo della fisioterapia<\/i><\/b><span style=\"font-weight: 400;\">, dove \u00e8 intervenuto in collegamento anche il Ministro della Salute Speranza, annunciando di aver firmato il decreto che ufficialmente istituisce la Federazione nazionale degli Ordini della professione dei Fisioterapisti che entrano nelle Professioni Sanitarie.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sedicesima edizione della World Confederation for Physical Therapy (WP \u2013 World Physiotherapy), che si tiene ogni 8 settembre, quest\u2019anno pone l\u2019accento su una patologia che si stima, affligga circa 520 milioni di persone in tutto il mondo: l\u2019Osteoartrite, 11\u00b0 causa di disabilit\u00e0 a livello mondiale.\u00a0 L\u2019Osteoartrite \u00e8 una malattia cronica che spesso \u00e8 associata [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":10593,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[867,1061,1062,260,592],"class_list":["post-10591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-clienti","tag-noticiasskuola","tag-unicamillus-international-medical-university","tag-1062","tag-centri-di-formazione","tag-centri-emagister"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>8 settembre: Giornata Mondiale della Fisioterapia - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8 settembre: Giornata Mondiale della Fisioterapia - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"La sedicesima edizione della World Confederation for Physical Therapy (WP \u2013 World Physiotherapy), che si tiene ogni 8 settembre, quest\u2019anno pone l\u2019accento su una patologia che si stima, affligga circa 520 milioni di persone in tutto il mondo: l\u2019Osteoartrite, 11\u00b0 causa di disabilit\u00e0 a livello mondiale.\u00a0 L\u2019Osteoartrite \u00e8 una malattia cronica che spesso \u00e8 associata [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-03T12:58:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-04T16:01:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/10\/tirocinanti-fisioterapia-UniCamillus.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/8-settembre-giornata-mondiale-della-fisioterapia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/8-settembre-giornata-mondiale-della-fisioterapia\\\/\"},\"author\":{\"name\":\"Redazione Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\"},\"headline\":\"8 settembre: Giornata Mondiale della Fisioterapia\",\"datePublished\":\"2022-10-03T12:58:54+00:00\",\"dateModified\":\"2022-10-04T16:01:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/8-settembre-giornata-mondiale-della-fisioterapia\\\/\"},\"wordCount\":251,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/8-settembre-giornata-mondiale-della-fisioterapia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/tirocinanti-fisioterapia-UniCamillus.png\",\"keywords\":[\"noticiasSkuola\",\"UniCamillus \u2013 International Medical University\",\"99992269674249392522766775092644\",\"Centri di Formazione\",\"centri emagister\"],\"articleSection\":[\"I Nostri Clienti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/8-settembre-giornata-mondiale-della-fisioterapia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/8-settembre-giornata-mondiale-della-fisioterapia\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/8-settembre-giornata-mondiale-della-fisioterapia\\\/\",\"name\":\"8 settembre: Giornata Mondiale della Fisioterapia - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/8-settembre-giornata-mondiale-della-fisioterapia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/8-settembre-giornata-mondiale-della-fisioterapia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/tirocinanti-fisioterapia-UniCamillus.png\",\"datePublished\":\"2022-10-03T12:58:54+00:00\",\"dateModified\":\"2022-10-04T16:01:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/8-settembre-giornata-mondiale-della-fisioterapia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/8-settembre-giornata-mondiale-della-fisioterapia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/8-settembre-giornata-mondiale-della-fisioterapia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/tirocinanti-fisioterapia-UniCamillus.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/tirocinanti-fisioterapia-UniCamillus.png\",\"width\":940,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/8-settembre-giornata-mondiale-della-fisioterapia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Nostri Clienti\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/i-nostri-clienti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"8 settembre: Giornata Mondiale della Fisioterapia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\",\"name\":\"Redazione Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Redazione Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/redazione-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"8 settembre: Giornata Mondiale della Fisioterapia - Emagister Blog Italia","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"8 settembre: Giornata Mondiale della Fisioterapia - Emagister Blog Italia","og_description":"La sedicesima edizione della World Confederation for Physical Therapy (WP \u2013 World Physiotherapy), che si tiene ogni 8 settembre, quest\u2019anno pone l\u2019accento su una patologia che si stima, affligga circa 520 milioni di persone in tutto il mondo: l\u2019Osteoartrite, 11\u00b0 causa di disabilit\u00e0 a livello mondiale.\u00a0 L\u2019Osteoartrite \u00e8 una malattia cronica che spesso \u00e8 associata [&hellip;]","og_url":"https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2022-10-03T12:58:54+00:00","article_modified_time":"2022-10-04T16:01:13+00:00","og_image":[{"width":940,"height":470,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/10\/tirocinanti-fisioterapia-UniCamillus.png","type":"image\/png"}],"author":"Redazione Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Redazione Emagister","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/"},"author":{"name":"Redazione Emagister","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897"},"headline":"8 settembre: Giornata Mondiale della Fisioterapia","datePublished":"2022-10-03T12:58:54+00:00","dateModified":"2022-10-04T16:01:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/"},"wordCount":251,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/10\/tirocinanti-fisioterapia-UniCamillus.png","keywords":["noticiasSkuola","UniCamillus \u2013 International Medical University","99992269674249392522766775092644","Centri di Formazione","centri emagister"],"articleSection":["I Nostri Clienti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/","url":"https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/","name":"8 settembre: Giornata Mondiale della Fisioterapia - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/10\/tirocinanti-fisioterapia-UniCamillus.png","datePublished":"2022-10-03T12:58:54+00:00","dateModified":"2022-10-04T16:01:13+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/10\/tirocinanti-fisioterapia-UniCamillus.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/10\/tirocinanti-fisioterapia-UniCamillus.png","width":940,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/8-settembre-giornata-mondiale-della-fisioterapia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"I Nostri Clienti","item":"https:\/\/www.emagister.it\/blog\/category\/i-nostri-clienti\/"},{"@type":"ListItem","position":3,"name":"8 settembre: Giornata Mondiale della Fisioterapia"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897","name":"Redazione Emagister","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Redazione Emagister"},"url":"https:\/\/www.emagister.it\/blog\/author\/redazione-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/10591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=10591"}],"version-history":[{"count":2,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/10591\/revisions"}],"predecessor-version":[{"id":10595,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/10591\/revisions\/10595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/10593"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=10591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=10591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=10591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}