{"id":10731,"date":"2023-02-01T16:26:47","date_gmt":"2023-02-01T16:26:47","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=10731"},"modified":"2023-02-01T16:26:47","modified_gmt":"2023-02-01T16:26:47","slug":"come-insegnare-linglese-ai-bambini-piccoli","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/","title":{"rendered":"Come insegnare l\u2019inglese ai bambini piccoli"},"content":{"rendered":"<p>Internet, la velocit\u00e0 dei mezzi di trasporto e le possibilit\u00e0 di viaggiare low cost hanno definitivamente abbattuto le barriere che, un tempo, limitavano la frequenza di connessione con i Paesi esteri. \u00c8 ormai evidente l\u2019importanza di\u00a0<strong>conoscere una o pi\u00f9 lingue straniere<\/strong>\u00a0per studiare, ma anche per trovare lavoro in un mondo sempre pi\u00f9 globalizzato.<\/p>\n<p>Le nuove generazioni crescono ormai ascoltando e parlando, fin dai primi mesi di vita, almeno la lingua inglese, con la speranza di assimilare quante pi\u00f9 competenze linguistiche possibili.<\/p>\n<p>L\u2019aspetto interessante \u00e8 proprio la modalit\u00e0 con la quale sempre pi\u00f9 insegnanti di inglese si pongono nei confronti dei bambini pi\u00f9 piccoli: laboratori e lezioni, infatti, vengono strutturati in modo tale da favorire un apprendimento naturale e spontaneo.<\/p>\n<h2><strong>Perch\u00e9 insegnare l\u2019inglese ai pi\u00f9 piccoli?<\/strong><\/h2>\n<p>Oggi pi\u00f9 che mai, l\u2019inglese \u00e8 una lingua fondamentale per comunicare con il mondo che ci circonda. Tantissime scuole, corsi universitari o di specializzazione propongono una formazione internazionale in lingua inglese, cos\u00ec come <em>workshop<\/em>, viaggi erasmus e altre esperienze all\u2019estero.<\/p>\n<p><span style=\"font-weight: 300;\"><a href=\"https:\/\/www.emagister.it\/corsi_istituto_cortivo-ef60980.htm\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-9709 size-full\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/02\/m-23.jpg\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/span><\/p>\n<p>Basterebbe anche solo questo motivo per convincersi di quanto sia importante insegnare l\u2019inglese ai bambini piccoli, gi\u00e0 mentre frequentano l\u2019Asilo. Se poi consideriamo il fatto che\u00a0<strong>l\u2019inglese \u00e8 diventato parte integrante di qualsiasi lavoro<\/strong>, i dubbi si esauriscono in fretta e le ragioni per investire nelle competenze linguistiche dei bambini aumentano a dismisura.<\/p>\n<h2><strong>L\u2019approccio ideale per insegnare l\u2019inglese ai bambini\u00a0<\/strong><\/h2>\n<p>Sappiamo che i bambini imparano prima di tutto per imitazione, ascoltando e osservando gli adulti, i loro coetanei, i fratellini e le sorelline. L\u2019approccio ideale per insegnare ai piccoli una lingua straniera, quindi, si basa sulla pratica periodica o addirittura quotidiana.<\/p>\n<p>Non serve fare grandi discorsi o preparare lezioni teoriche troppo complesse da elaborare per i bambini dell\u2019Asilo, basta ad esempio trasformare un gioco motorio in\u00a0<strong>un\u2019occasione per scambiare qualche primo vocabolo in inglese<\/strong>.<\/p>\n<h2><strong>Idee per le lezioni di inglese ai bambini dell\u2019Asilo<\/strong><\/h2>\n<p>All\u2019Asilo, i giochi in lingua inglese possono riprendere le stesse attivit\u00e0 previste in italiano, ma con l\u2019utilizzo di un vocabolario diverso. Ad esempio, una canzoncina in cerchio che propone diversi movimenti da pronunciare in inglese e da eseguire con le mani, le braccia, le gambe; oppure una staffetta con oggetti colorati di cui bisogna pronunciare il nome a ogni passaggio.<\/p>\n<p>Per favorire l\u2019apprendimento dell\u2019inglese nei bambini, le proposte in inglese possono proseguire anche a casa con piccole storie in lingua o pranzi a tema in perfetto english style ?<\/p>\n<p>Vuoi capire ancora meglio come insegnare l\u2019inglese ai bambini? Iscriviti ai <strong>corsi dell&#8217;Istituto Cortivo\u00a0<\/strong>e diventa <a href=\"https:\/\/www.emagister.it\/corso_assistente_all_infanzia-ec2444953.htm\"><strong>Assistente all\u2019Infanzia<\/strong><\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Internet, la velocit\u00e0 dei mezzi di trasporto e le possibilit\u00e0 di viaggiare low cost hanno definitivamente abbattuto le barriere che, un tempo, limitavano la frequenza di connessione con i Paesi esteri. \u00c8 ormai evidente l\u2019importanza di\u00a0conoscere una o pi\u00f9 lingue straniere\u00a0per studiare, ma anche per trovare lavoro in un mondo sempre pi\u00f9 globalizzato. Le nuove [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":10732,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[260,592,867,1064,1065],"class_list":["post-10731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-clienti","tag-centri-di-formazione","tag-centri-emagister","tag-noticiasskuola","tag-1064","tag-istituto-cortivo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come insegnare l\u2019inglese ai bambini piccoli - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come insegnare l\u2019inglese ai bambini piccoli - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"Internet, la velocit\u00e0 dei mezzi di trasporto e le possibilit\u00e0 di viaggiare low cost hanno definitivamente abbattuto le barriere che, un tempo, limitavano la frequenza di connessione con i Paesi esteri. \u00c8 ormai evidente l\u2019importanza di\u00a0conoscere una o pi\u00f9 lingue straniere\u00a0per studiare, ma anche per trovare lavoro in un mondo sempre pi\u00f9 globalizzato. Le nuove [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-01T16:26:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2023\/02\/GettyImages-679417794.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-insegnare-linglese-ai-bambini-piccoli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-insegnare-linglese-ai-bambini-piccoli\\\/\"},\"author\":{\"name\":\"Redazione Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\"},\"headline\":\"Come insegnare l\u2019inglese ai bambini piccoli\",\"datePublished\":\"2023-02-01T16:26:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-insegnare-linglese-ai-bambini-piccoli\\\/\"},\"wordCount\":440,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-insegnare-linglese-ai-bambini-piccoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/GettyImages-679417794.jpg\",\"keywords\":[\"Centri di Formazione\",\"centri emagister\",\"noticiasSkuola\",\"36672020092057507051685157494565\",\"Istituto Cortivo\"],\"articleSection\":[\"I Nostri Clienti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-insegnare-linglese-ai-bambini-piccoli\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-insegnare-linglese-ai-bambini-piccoli\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-insegnare-linglese-ai-bambini-piccoli\\\/\",\"name\":\"Come insegnare l\u2019inglese ai bambini piccoli - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-insegnare-linglese-ai-bambini-piccoli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-insegnare-linglese-ai-bambini-piccoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/GettyImages-679417794.jpg\",\"datePublished\":\"2023-02-01T16:26:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-insegnare-linglese-ai-bambini-piccoli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-insegnare-linglese-ai-bambini-piccoli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-insegnare-linglese-ai-bambini-piccoli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/GettyImages-679417794.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/GettyImages-679417794.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-insegnare-linglese-ai-bambini-piccoli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Nostri Clienti\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/i-nostri-clienti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Come insegnare l\u2019inglese ai bambini piccoli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\",\"name\":\"Redazione Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Redazione Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/redazione-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come insegnare l\u2019inglese ai bambini piccoli - Emagister Blog Italia","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Come insegnare l\u2019inglese ai bambini piccoli - Emagister Blog Italia","og_description":"Internet, la velocit\u00e0 dei mezzi di trasporto e le possibilit\u00e0 di viaggiare low cost hanno definitivamente abbattuto le barriere che, un tempo, limitavano la frequenza di connessione con i Paesi esteri. \u00c8 ormai evidente l\u2019importanza di\u00a0conoscere una o pi\u00f9 lingue straniere\u00a0per studiare, ma anche per trovare lavoro in un mondo sempre pi\u00f9 globalizzato. Le nuove [&hellip;]","og_url":"https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2023-02-01T16:26:47+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2023\/02\/GettyImages-679417794.jpg","type":"image\/jpeg"}],"author":"Redazione Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Redazione Emagister","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/"},"author":{"name":"Redazione Emagister","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897"},"headline":"Come insegnare l\u2019inglese ai bambini piccoli","datePublished":"2023-02-01T16:26:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/"},"wordCount":440,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2023\/02\/GettyImages-679417794.jpg","keywords":["Centri di Formazione","centri emagister","noticiasSkuola","36672020092057507051685157494565","Istituto Cortivo"],"articleSection":["I Nostri Clienti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/","url":"https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/","name":"Come insegnare l\u2019inglese ai bambini piccoli - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2023\/02\/GettyImages-679417794.jpg","datePublished":"2023-02-01T16:26:47+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2023\/02\/GettyImages-679417794.jpg","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2023\/02\/GettyImages-679417794.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/come-insegnare-linglese-ai-bambini-piccoli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"I Nostri Clienti","item":"https:\/\/www.emagister.it\/blog\/category\/i-nostri-clienti\/"},{"@type":"ListItem","position":3,"name":"Come insegnare l\u2019inglese ai bambini piccoli"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897","name":"Redazione Emagister","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Redazione Emagister"},"url":"https:\/\/www.emagister.it\/blog\/author\/redazione-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/10731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=10731"}],"version-history":[{"count":2,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/10731\/revisions"}],"predecessor-version":[{"id":10803,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/10731\/revisions\/10803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/10732"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=10731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=10731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=10731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}