{"id":11463,"date":"2023-08-08T07:04:49","date_gmt":"2023-08-08T07:04:49","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=11463"},"modified":"2023-08-08T07:04:49","modified_gmt":"2023-08-08T07:04:49","slug":"unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/","title":{"rendered":"UniCamillus ai Mondiali di Scherma: Francesco Pierri, studente del master in Posturologia, ha partecipato come massoterapista all\u2019ultima edizione di Milano 2023"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">L\u2019edizione 2023 dei <\/span><b>Mondiali di Scherma<\/b><span style=\"font-weight: 400;\"> si \u00e8 tenuta a Milano dal 22 al 30 luglio scorso. Il <\/span><b>comitato organizzatore<\/b><span style=\"font-weight: 400;\"> e il <\/span><b>CONI<\/b><span style=\"font-weight: 400;\"> hanno selezionato anche <\/span><b>Francesco Maria Pierri<\/b><span style=\"font-weight: 400;\"> tra i professionisti sanitari messi a disposizione degli atleti. Giovane massoterapista (classe 1995), specializzato in tecniche delle attivit\u00e0 motorie preventive, il dottor Pierri frequenta attualmente il <\/span><b>master di I livello in Posturologia Clinica presso l\u2019Universit\u00e0 Medica Internazionale di Roma<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h3><b>Cosa ha rappresentato per te questa esperienza da un punto di vista professionale e umano?\u00a0<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">\u201cDifficile raccontare le emozioni che ho provato. Mai avrei pensato quando ho iniziato questo <\/span><b>percorso di studi<\/b><span style=\"font-weight: 400;\"> di trovarmi un giorno a lavorare in una <\/span><b>manifestazione mondiale<\/b><span style=\"font-weight: 400;\">, n\u00e9 tanto meno di diventare parte attiva degli eventi. Invece mi sono trovato a stretto contatto con gli atleti, con i quali ho interagito autonomamente, valutando con loro i trattamenti da svolgere, senza dover rispondere a supervisioni di qualcun altro come invece spesso capita quando si fanno tirocini formativi. Questa \u00e8 stata una vera e propria <\/span><b>esperienza lavorativa<\/b><span style=\"font-weight: 400;\">, dove mi sono potuto mettere alla prova, per di pi\u00f9 in un contesto di alto livello\u201d.<\/span><\/p>\n<h3><b>Quali interventi pratici e trattamenti ti sei trovato a dover svolgere con gli atleti?\u00a0<\/b><\/h3>\n<h4><b><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.emagister.it\/corsi_unicamillus_international_medical_university-ef106220.htm\" target=\"_blank\" rel=\"noopener noopenernofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.emagister.it\/assets\/it\/logos\/centro\/id\/106220\/size\/l.jpg\" alt=\"UniCamillus \u2013 International Medical University\" width=\"215\" height=\"143\" \/><\/a><\/span><\/b><\/h4>\n<p><span style=\"font-weight: 400;\">\u201cPrevalentemente ho svolto interventi di <\/span><b>tecar-terapia<\/b><span style=\"font-weight: 400;\">, <\/span><b>laser-terapia<\/b><span style=\"font-weight: 400;\">, <\/span><b>bendaggi pregara<\/b><span style=\"font-weight: 400;\"> e <\/span><b>massaggi postgara<\/b><span style=\"font-weight: 400;\">. Per fortuna non ci sono stati infortuni particolarmente importanti per gli atleti. Erano per lo pi\u00f9 loro stessi a chiedere assistenza se, soprattutto dopo gli incontri, avvertivano fastidi fisici alla schiena o alle braccia, comunque abbastanza frequenti nella pratica della Scherma\u201d.<\/span><\/p>\n<h3><b>In che modo il Master che attualmente sta seguendo in UniCamillus ti \u00e8 stato utile in questa occasione e come lo potr\u00e0 essere per il tuo futuro professionale?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">\u201cNella <\/span><b>medicina<\/b><span style=\"font-weight: 400;\"> e nella <\/span><b>cura della salute<\/b><span style=\"font-weight: 400;\"> in generale tutto \u00e8 collegato intrinsecamente, quindi tutto quello che ho studiato in questo campo lo ho poi ritrovato nella pratica e mi \u00e8 stato utile. Intervenire sulla postura, che \u00e8 ci\u00f2 che sto approfondendo ora in <\/span><b>UniCamillus<\/b><span style=\"font-weight: 400;\">, \u00e8 importante per un atleta tanto quanto lo pu\u00f2 essere un qualunque altro trattamento pre o post gara o anche per recuperare al meglio dopo un problema fisico. D\u2019altronde la <\/span><b>fisioterapia<\/b><span style=\"font-weight: 400;\"> \u00e8 una materia in continua evoluzione. Se pensiamo ad esempio a tutte le varie problematiche che stanno sorgendo sempre pi\u00f9 nelle persone per le <\/span><b>posture scorrette durante l\u2019attivit\u00e0 lavorativa<\/b><span style=\"font-weight: 400;\"> o nell\u2019utilizzo continuo dei tablet e degli smartphone, per un fisioterapista \u00e8 diventato molto importante avere una conoscenza diffusa anche di come intervenire per correggere i difetti posturali. \u00c8 necessario conoscere determinati aspetti della <\/span><b>posturologia<\/b><span style=\"font-weight: 400;\">, della <\/span><b>biomeccanica del corpo<\/b><span style=\"font-weight: 400;\"> per poi poter applicare queste conoscenze alla massoterapia\u201d.<\/span><\/p>\n<h3><b>Quali aspettative e obiettivi hai per il tuo profilo professionale?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">\u201cIl <\/span><b>mondo dello sport<\/b><span style=\"font-weight: 400;\"> \u00e8 quello che mi emoziona di pi\u00f9. \u00c8 un continuo divenire, perch\u00e9 non si lavora in maniera standardizzata, ma ci si trova a dover trattare ogni atleta in maniera diversa, anche a seconda dell\u2019attivit\u00e0 sportiva. Non si sa mai cosa ci si potrebbe trovare a dover trattare e l\u2019attivit\u00e0 professionale di un <\/span><b>fisioterapista<\/b><span style=\"font-weight: 400;\"> in questo modo pu\u00f2 diventare pi\u00f9 dinamica e variegata. Mi piacerebbe molto proseguire in questo campo, anche se chiaramente non ci si pu\u00f2 focalizzare in un singolo ambito. Non mi pongo per\u00f2 obiettivi precisi. Voglio cogliere tutte le occasioni che mi capiteranno e chiss\u00e0, magari un giorno mi ritrover\u00f2 persino a lavorare alle <\/span><b>Olimpiadi<\/b><span style=\"font-weight: 400;\">!\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L\u2019augurio per Francesco \u00e8 che possa davvero riuscirci.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019edizione 2023 dei Mondiali di Scherma si \u00e8 tenuta a Milano dal 22 al 30 luglio scorso. Il comitato organizzatore e il CONI hanno selezionato anche Francesco Maria Pierri tra i professionisti sanitari messi a disposizione degli atleti. Giovane massoterapista (classe 1995), specializzato in tecniche delle attivit\u00e0 motorie preventive, il dottor Pierri frequenta attualmente il [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":11464,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[592,867,1061,1062,1287],"class_list":["post-11463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-clienti","tag-centri-emagister","tag-noticiasskuola","tag-unicamillus-international-medical-university","tag-1062","tag-centri-di-fromazione"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UniCamillus ai Mondiali di Scherma: Francesco Pierri, studente del master in Posturologia, ha partecipato come massoterapista all\u2019ultima edizione di Milano 2023 - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UniCamillus ai Mondiali di Scherma: Francesco Pierri, studente del master in Posturologia, ha partecipato come massoterapista all\u2019ultima edizione di Milano 2023 - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"L\u2019edizione 2023 dei Mondiali di Scherma si \u00e8 tenuta a Milano dal 22 al 30 luglio scorso. Il comitato organizzatore e il CONI hanno selezionato anche Francesco Maria Pierri tra i professionisti sanitari messi a disposizione degli atleti. Giovane massoterapista (classe 1995), specializzato in tecniche delle attivit\u00e0 motorie preventive, il dottor Pierri frequenta attualmente il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-08T07:04:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2023\/08\/Pierri_SCherma_UniCamillus-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\\\/\"},\"author\":{\"name\":\"Redazione Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\"},\"headline\":\"UniCamillus ai Mondiali di Scherma: Francesco Pierri, studente del master in Posturologia, ha partecipato come massoterapista all\u2019ultima edizione di Milano 2023\",\"datePublished\":\"2023-08-08T07:04:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\\\/\"},\"wordCount\":573,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Pierri_SCherma_UniCamillus-1.png\",\"keywords\":[\"centri emagister\",\"noticiasSkuola\",\"UniCamillus \u2013 International Medical University\",\"99992269674249392522766775092644\",\"centri di fromazione\"],\"articleSection\":[\"I Nostri Clienti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\\\/\",\"name\":\"UniCamillus ai Mondiali di Scherma: Francesco Pierri, studente del master in Posturologia, ha partecipato come massoterapista all\u2019ultima edizione di Milano 2023 - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Pierri_SCherma_UniCamillus-1.png\",\"datePublished\":\"2023-08-08T07:04:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Pierri_SCherma_UniCamillus-1.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Pierri_SCherma_UniCamillus-1.png\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Nostri Clienti\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/i-nostri-clienti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"UniCamillus ai Mondiali di Scherma: Francesco Pierri, studente del master in Posturologia, ha partecipato come massoterapista all\u2019ultima edizione di Milano 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\",\"name\":\"Redazione Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Redazione Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/redazione-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UniCamillus ai Mondiali di Scherma: Francesco Pierri, studente del master in Posturologia, ha partecipato come massoterapista all\u2019ultima edizione di Milano 2023 - Emagister Blog Italia","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"UniCamillus ai Mondiali di Scherma: Francesco Pierri, studente del master in Posturologia, ha partecipato come massoterapista all\u2019ultima edizione di Milano 2023 - Emagister Blog Italia","og_description":"L\u2019edizione 2023 dei Mondiali di Scherma si \u00e8 tenuta a Milano dal 22 al 30 luglio scorso. Il comitato organizzatore e il CONI hanno selezionato anche Francesco Maria Pierri tra i professionisti sanitari messi a disposizione degli atleti. Giovane massoterapista (classe 1995), specializzato in tecniche delle attivit\u00e0 motorie preventive, il dottor Pierri frequenta attualmente il [&hellip;]","og_url":"https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2023-08-08T07:04:49+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2023\/08\/Pierri_SCherma_UniCamillus-1.png","type":"image\/png"}],"author":"Redazione Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Redazione Emagister","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/"},"author":{"name":"Redazione Emagister","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897"},"headline":"UniCamillus ai Mondiali di Scherma: Francesco Pierri, studente del master in Posturologia, ha partecipato come massoterapista all\u2019ultima edizione di Milano 2023","datePublished":"2023-08-08T07:04:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/"},"wordCount":573,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2023\/08\/Pierri_SCherma_UniCamillus-1.png","keywords":["centri emagister","noticiasSkuola","UniCamillus \u2013 International Medical University","99992269674249392522766775092644","centri di fromazione"],"articleSection":["I Nostri Clienti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/","url":"https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/","name":"UniCamillus ai Mondiali di Scherma: Francesco Pierri, studente del master in Posturologia, ha partecipato come massoterapista all\u2019ultima edizione di Milano 2023 - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2023\/08\/Pierri_SCherma_UniCamillus-1.png","datePublished":"2023-08-08T07:04:49+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2023\/08\/Pierri_SCherma_UniCamillus-1.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2023\/08\/Pierri_SCherma_UniCamillus-1.png","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/unicamillus-ai-mondiali-di-scherma-francesco-pierri-studente-del-master-in-posturologia-ha-partecipato-come-massoterapista-allultima-edizione-di-milano-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"I Nostri Clienti","item":"https:\/\/www.emagister.it\/blog\/category\/i-nostri-clienti\/"},{"@type":"ListItem","position":3,"name":"UniCamillus ai Mondiali di Scherma: Francesco Pierri, studente del master in Posturologia, ha partecipato come massoterapista all\u2019ultima edizione di Milano 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897","name":"Redazione Emagister","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Redazione Emagister"},"url":"https:\/\/www.emagister.it\/blog\/author\/redazione-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/11463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=11463"}],"version-history":[{"count":4,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/11463\/revisions"}],"predecessor-version":[{"id":11975,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/11463\/revisions\/11975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/11464"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=11463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=11463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=11463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}