{"id":357,"date":"2014-11-06T17:01:34","date_gmt":"2014-11-06T17:01:34","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=357"},"modified":"2014-11-06T17:01:34","modified_gmt":"2014-11-06T17:01:34","slug":"come-affrontare-un-colloquio-di-lavoro-in-inglese","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/","title":{"rendered":"Come affrontare un colloquio di lavoro in inglese"},"content":{"rendered":"<p>Hai appena saputo che il colloquio di lavoro per cui sei stato selezionato \u00e8 in inglese? Se sei bilingue,<br \/>\nprobabilmente non sar\u00e0 un problema, ma se il tuo livello \u00e8 inglese <a href=\"https:\/\/www.emagister.it\/corsi_inglese_avanzato_online_-kwonline-34421.htm?pfichas=7507\" target=\"_blank\">medio-alto<\/a>, dovrai prepararti per<br \/>\naffrontare le domande dell&#8217;intervistatore. Obiettivo di questo post \u00e8 svelarti le domande pi\u00f9 utilizzate in un colloquio in inglese e offrirti alcuni consigli utili per superare con successo il tuo colloquio. Are you ready?<\/p>\n<p><!--more--><\/p>\n<p><strong>Quale sono le domande pi\u00f9 comuni in un colloquio di lavoro in inglese?<\/strong><\/p>\n<p>Prepararti su queste risposte significa prepararti solo una parte del colloquio, ci saranno altre domande<br \/>\nche verranno fuori dalle tue risposte ed \u00e8 molto importante concentrarti sulla forma con cui parlerai<br \/>\ndelle tue abilit\u00e0 e delle conoscenze.<\/p>\n<p><strong>\u2022 Tell me about yourself (parlami di te):<\/strong> Cerca di parlare delle esperienze che hanno una<br \/>\nrelazione con il lavoro in questione, che credi ti possano essere utili per il buon andamento del colloquio.<\/p>\n<p><strong>\u2022 What are your strenghts? (Quali sono i tuoi punti forti):<\/strong> Elenca le tue qualit\u00e0 e aggiungi un esempio o un aneddoto che possa potenziarle.<\/p>\n<p><strong>\u2022 What is your weakness? Qual \u00e8 la tua maggiore debolezza?):<\/strong> Si tratta di rispondere con un aspetto che, anche se negativo, possa apparire positivo.<\/p>\n<p><strong>\u2022 Why have you been unemployed for such a long time? (Perch\u00e9 \u00e8 stato disoccupato tanto<br \/>\ntempo):<\/strong> Cerca di riempire gli spazi in cui non hai lavorato con altre attivit\u00e0 come: corsi che hai fatto, i lavori che hai realizzato in forma sporadica, se hai creato un blog ecc.<\/p>\n<p><strong>\u2022 How do you see yourself in five years from now? (Come ti vedi tra 5 anni?):<\/strong> Cerca di adattare la risposta al profilo richiesto dal lavoro in questione.<\/p>\n<p><strong>\u2022 What do you know about the type of work we do?(Cosa sai di noi, di cosa ci occupiamo?): <\/strong> Questo punto \u00e8 molto importante, parla della tua esperienza in un impiego simile, della tua formazione e competenze in questa area specifica.<br \/>\n<strong><br \/>\n\u2022 Why do you think you would do well at this job? (Perch\u00e9 pensi che potresti essere adatto a<br \/>\nquesto lavoro?):<\/strong> Parla delle tue competenze, della tua esperienza e formazione, e di tutto ci\u00f2 che potrebbe essere utile per ottenere il posto.<\/p>\n<p><strong>Cosa fare prima del colloquio<\/strong><\/p>\n<p><strong>1-<\/strong> Prima di tutto ti consigliamo di prepararti prima di qualsiasi tipo di colloquio. Devi informarti sull&#8217;azienda, sul settore al quale appartiene, sulla posizione lavorativa che offre, il profilo della persona che cercano, ecc.<\/p>\n<p><strong>2-<\/strong> Quando avrai risposto a tutte le domande in italiano, traducile in inglese e crea una lista di tutte le parole specifiche che sicuramente saranno contenute nelle domande o faranno parte del colloquio in generale. C&#8217;\u00e8 sempre un vocabolario riguardante il settore specifico.<\/p>\n<p><strong>3- <\/strong>Quando avrai terminato con \u201cle domande probabili\u201d prova a fare pratica con una persona bilingue o nativa, che ti possa consigliare e correggerti. Se stai studiando inglese, puoi chiedere una mano al tuo professore o entrare su un forum su internet per praticare.<\/p>\n<p><strong>Durante il colloquio<\/strong><\/p>\n<p><strong>1- <\/strong>Ascolta attentamente le domande, ti sar\u00e0 utile per preparare meglio le risposte e potrai ridurre la possibilit\u00e0 di commettere errori. Inoltre, potrai testare il livello di inglese dell&#8217;intervistatore e nel caso in cui fosse simile al tuo ti sentirai pi\u00f9 sicuro nel rispondere.<\/p>\n<p><strong>2-<\/strong> Non esitare a chiedere che ti siano ripetute le domande se non comprendi qualcosa, in una situazione di tensione come un colloquio di lavoro \u00e8 facile confondersi o non capire bene. Se ti dovesse succedere chiedi pure al tuo interlocutore di ripetere la domanda. Cos\u00ec potrai anche guadagnare tempo per pensare alla risposta corretta.<\/p>\n<p><strong>3-<\/strong> Rispondi alle domande senza precipitarti parlando in maniera pausata. Non ti concentrare sul tuo accento o sull&#8217;imbarazzo di parlare in inglese, ci\u00f2 che viene valutato in questo tipo di colloqui \u00e8 la tua capacit\u00e0 di comunicazione, per questo \u00e8 importante che rispondere parlando lentamente, in modo da comprendere il contenuto della tua risposta. Se riesci a comunicare le tue risposte con sicurezza, avrai superato con successo il colloquio.<\/p>\n<p><strong>4-<\/strong> Cerca di tenere sotto controllo i nervi, non \u00e8 facile, indipendentemente dal fatto di dominare o no la lingua. Non lasciare che la tensione ti giochi un brutto tiro. Respira profondamente e credi nelle tue capacit\u00e0.<\/p>\n<p>Buona fortuna! O good luck!<\/p>\n<table border=\"1\" cellspacing=\"2\" cellpadding=\"2\">\n<tbody>\n<tr>\n<td width=\"140\" height=\"192\"><a href=\"https:\/\/www.emagister.it\/blog\/?attachment_id=599\" rel=\"attachment wp-att-599\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-599 aligncenter\" alt=\"daniella daza\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2014\/10\/daniella-daza.jpeg\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2014\/10\/daniella-daza.jpeg 100w, https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2014\/10\/daniella-daza-80x80.jpeg 80w, https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2014\/10\/daniella-daza-50x50.jpeg 50w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a><\/td>\n<td><strong>Daniella Daza.<\/strong>Giornalista. Content Marketing Manager, specializzata nella progettazione, implementazione e applicazione di strategie di Marketing dei Contenuti. Social Media e Community Manager con esperienza nella definizione, implementazione e razionalizzazione dei profili aziendali sui social network. Specializzata in gestione di bloggers professionisti. Profonda conoscenza dell\u2019outsourcing dei contenuti. Costruzione e segmentazione di newsletter.<\/td>\n<\/tr>\n<tr>\n<td><strong>LinkedIn<\/strong><\/td>\n<td><a href=\"https:\/\/www.linkedin.com\/in\/danielladaza\" target=\"_blank\">https:\/\/www.linkedin.com\/in\/danielladaza<\/a><\/td>\n<\/tr>\n<tr>\n<td><strong>Twitter:<\/strong><\/td>\n<td><a href=\"https:\/\/twitter.com\/danydaza\" target=\"_blank\">https:\/\/twitter.com\/danydaza<\/a><\/td>\n<\/tr>\n<tr>\n<td><strong>Tradotto da:<\/strong><\/td>\n<td>Alessia Surace<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Hai appena saputo che il colloquio di lavoro per cui sei stato selezionato \u00e8 in inglese? Se sei bilingue, probabilmente non sar\u00e0 un problema, ma se il tuo livello \u00e8 inglese medio-alto, dovrai prepararti per affrontare le domande dell&#8217;intervistatore. Obiettivo di questo post \u00e8 svelarti le domande pi\u00f9 utilizzate in un colloquio in inglese e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":371,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lavoro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come affrontare un colloquio di lavoro in inglese - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come affrontare un colloquio di lavoro in inglese - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"Hai appena saputo che il colloquio di lavoro per cui sei stato selezionato \u00e8 in inglese? Se sei bilingue, probabilmente non sar\u00e0 un problema, ma se il tuo livello \u00e8 inglese medio-alto, dovrai prepararti per affrontare le domande dell&#8217;intervistatore. Obiettivo di questo post \u00e8 svelarti le domande pi\u00f9 utilizzate in un colloquio in inglese e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-06T17:01:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2014\/07\/ingles.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alessia Surace\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alessia Surace\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-affrontare-un-colloquio-di-lavoro-in-inglese\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-affrontare-un-colloquio-di-lavoro-in-inglese\\\/\"},\"author\":{\"name\":\"Alessia Surace\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/5b849ba90a269fe647afa18739b1d612\"},\"headline\":\"Come affrontare un colloquio di lavoro in inglese\",\"datePublished\":\"2014-11-06T17:01:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-affrontare-un-colloquio-di-lavoro-in-inglese\\\/\"},\"wordCount\":766,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-affrontare-un-colloquio-di-lavoro-in-inglese\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/ingles.jpg\",\"articleSection\":[\"Ricerca di Lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-affrontare-un-colloquio-di-lavoro-in-inglese\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-affrontare-un-colloquio-di-lavoro-in-inglese\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-affrontare-un-colloquio-di-lavoro-in-inglese\\\/\",\"name\":\"Come affrontare un colloquio di lavoro in inglese - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-affrontare-un-colloquio-di-lavoro-in-inglese\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-affrontare-un-colloquio-di-lavoro-in-inglese\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/ingles.jpg\",\"datePublished\":\"2014-11-06T17:01:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-affrontare-un-colloquio-di-lavoro-in-inglese\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-affrontare-un-colloquio-di-lavoro-in-inglese\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-affrontare-un-colloquio-di-lavoro-in-inglese\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/ingles.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/ingles.jpg\",\"width\":580,\"height\":549},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-affrontare-un-colloquio-di-lavoro-in-inglese\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ricerca di Lavoro\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Come affrontare un colloquio di lavoro in inglese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/5b849ba90a269fe647afa18739b1d612\",\"name\":\"Alessia Surace\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00131b373f75cb661cc0f9201ac1d9df9552e977dc2e027168797d7cc97b130a?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00131b373f75cb661cc0f9201ac1d9df9552e977dc2e027168797d7cc97b130a?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00131b373f75cb661cc0f9201ac1d9df9552e977dc2e027168797d7cc97b130a?s=96&r=g\",\"caption\":\"Alessia Surace\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/alessia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come affrontare un colloquio di lavoro in inglese - Emagister Blog Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/","og_locale":"it_IT","og_type":"article","og_title":"Come affrontare un colloquio di lavoro in inglese - Emagister Blog Italia","og_description":"Hai appena saputo che il colloquio di lavoro per cui sei stato selezionato \u00e8 in inglese? Se sei bilingue, probabilmente non sar\u00e0 un problema, ma se il tuo livello \u00e8 inglese medio-alto, dovrai prepararti per affrontare le domande dell&#8217;intervistatore. Obiettivo di questo post \u00e8 svelarti le domande pi\u00f9 utilizzate in un colloquio in inglese e [&hellip;]","og_url":"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2014-11-06T17:01:34+00:00","og_image":[{"width":580,"height":549,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2014\/07\/ingles.jpg","type":"image\/jpeg"}],"author":"Alessia Surace","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Alessia Surace","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/"},"author":{"name":"Alessia Surace","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/5b849ba90a269fe647afa18739b1d612"},"headline":"Come affrontare un colloquio di lavoro in inglese","datePublished":"2014-11-06T17:01:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/"},"wordCount":766,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2014\/07\/ingles.jpg","articleSection":["Ricerca di Lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/","url":"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/","name":"Come affrontare un colloquio di lavoro in inglese - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2014\/07\/ingles.jpg","datePublished":"2014-11-06T17:01:34+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2014\/07\/ingles.jpg","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2014\/07\/ingles.jpg","width":580,"height":549},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/come-affrontare-un-colloquio-di-lavoro-in-inglese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"Ricerca di Lavoro","item":"https:\/\/www.emagister.it\/blog\/category\/lavoro\/"},{"@type":"ListItem","position":3,"name":"Come affrontare un colloquio di lavoro in inglese"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/5b849ba90a269fe647afa18739b1d612","name":"Alessia Surace","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/00131b373f75cb661cc0f9201ac1d9df9552e977dc2e027168797d7cc97b130a?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00131b373f75cb661cc0f9201ac1d9df9552e977dc2e027168797d7cc97b130a?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00131b373f75cb661cc0f9201ac1d9df9552e977dc2e027168797d7cc97b130a?s=96&r=g","caption":"Alessia Surace"},"url":"https:\/\/www.emagister.it\/blog\/author\/alessia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=357"}],"version-history":[{"count":8,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/357\/revisions"}],"predecessor-version":[{"id":645,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/357\/revisions\/645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/371"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}