{"id":5070,"date":"2020-01-17T08:21:13","date_gmt":"2020-01-17T08:21:13","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=5070"},"modified":"2020-01-17T13:28:32","modified_gmt":"2020-01-17T13:28:32","slug":"la-leadership-servant-il-nuovo-modo-di-essere-leader","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/","title":{"rendered":"La &#8220;Leadership Servant&#8221;, il nuovo modo di essere leader!"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Ti piacerebbe sapere come far crescere il tuo team e ottenere grandi risultati? <\/span><a href=\"https:\/\/www.emagister.it\/corsi_make_it-ef74422.htm\" target=\"_blank\" rel=\"noopener\"><i><span style=\"font-weight: 400;\"><strong>Make It So<\/strong><\/span><\/i><\/a><span style=\"font-weight: 400;\"> ti mostra come, continua a leggere questo articolo!\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00c8 possibile essere allo stesso tempo leader e servitori?<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Nel 1970 Robert Greenleaf, prendendo spunto da un personaggio presente in un romanzo di Herman Hesse, introduce il concetto di <\/span><b><i>leadership servant<\/i><\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Greenleaf ha conseguito far coesistere due concetti: guidare e servire. Fu il principio di un nuovo significato di <\/span><i><span style=\"font-weight: 400;\">leadership,<\/span><\/i><span style=\"font-weight: 400;\"> un innovativo stile manageriale in cui l\u2019obiettivo principale del <\/span><i><span style=\"font-weight: 400;\">leader<\/span><\/i><span style=\"font-weight: 400;\"> \u00e8 mettersi al servizio degli altri.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Il <\/span><i><span style=\"font-weight: 400;\">leader servant<\/span><\/i><span style=\"font-weight: 400;\"> si mette al servizio dei propri collaboratori, pone le loro necessit\u00e0 davanti a tutto, cerca di incitarli e spronarli per dare il meglio, aiutandoli a raggiungere le pi\u00f9 alte <\/span><i><span style=\"font-weight: 400;\">performance<\/span><\/i><span style=\"font-weight: 400;\"> possibili.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La <\/span><i><span style=\"font-weight: 400;\">leadership servant<\/span><\/i><span style=\"font-weight: 400;\"> ribalta le certezze precedenti, ora il capo esiste per servire il gruppo, non viceversa.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Guidare servendo<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">I collaboratori del <\/span><i><span style=\"font-weight: 400;\">leader servant<\/span><\/i><span style=\"font-weight: 400;\"> in che modo possono crescere come individui? \u00c8 questa la domanda che si pone Greenleaf. I concetti guidare e servire si intrecciano, un<\/span><i><span style=\"font-weight: 400;\"> leader servant<\/span><\/i><span style=\"font-weight: 400;\"> deve integrare queste due competenze per cercare di essere al timone dell\u2019organizzazione mettendosi al servizio dei collaboratori.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Se si mettono in campo qualit\u00e0 come la disponibilit\u00e0 e l\u2019autenticit\u00e0 si diventa un punto di riferimento chiaro e, se i valori di riferimento sono coerenti con i comportamenti, il <\/span><i><span style=\"font-weight: 400;\">leader servant <\/span><\/i><span style=\"font-weight: 400;\">si erge a modello di ispirazione per tutto il gruppo.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Come si raggiunge questo status?<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Bisogna prima di tutto avere e potenziare una <\/span><b>forte fiducia in se stessi<\/b><span style=\"font-weight: 400;\"> e nel proprio operato, spostando il focus sempre pi\u00f9 verso gli altri e non verso se stessi, in quanto la difesa del proprio<\/span><i><span style=\"font-weight: 400;\"> status<\/span><\/i><span style=\"font-weight: 400;\"> mette in secondo piano la crescita del lavoratore.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Un <\/span><i><span style=\"font-weight: 400;\">leader servant <\/span><\/i><span style=\"font-weight: 400;\">ascolta tanto, si confronta continuamente con i collaboratori e cerca di costruire una comunicazione costruttiva, efficace ed assertiva.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Questo agire permette di passare da una logica di controllo ad una di servizio, che fa riferimento alla cultura della cura.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Ma quali sono i benefici per i lavoratori?<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Tutto parte da una motivazione intrinseca. Questo differente approccio alla <\/span><i><span style=\"font-weight: 400;\">leadership <\/span><\/i><span style=\"font-weight: 400;\">potenzia e migliora il rapporto e la relazione tra capo e dipendente, che conduce ad un maggior impegno da parte del lavoratore per ricompensare la fiducia che il <\/span><i><span style=\"font-weight: 400;\">leade<\/span><\/i><span style=\"font-weight: 400;\">r ha posto nei propri confronti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">I <\/span><i><span style=\"font-weight: 400;\">leader servant<\/span><\/i><span style=\"font-weight: 400;\"> guardano al futuro e stabiliscono obiettivi a medio e lungo termine in condivisione con il<\/span><i><span style=\"font-weight: 400;\"> team,<\/span><\/i><span style=\"font-weight: 400;\"> ma il fattore pi\u00f9 importante \u00e8 che mettono i dipendenti davanti a tutto, anche prima dell\u2019organizzazione, stabilendo un orientamento incentrato sulla persona.<a href=\"https:\/\/www.emagister.it\/corsi_make_it-cen-74422.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-4585 size-full\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/11\/Make-It-So.png\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Questo approccio comporta che i lavoratori siano altamente responsabilizzati e fortemente motivati perch\u00e8 si sentono coinvolti in un progetto che percepiscono come proprio, si sentono orgogliosi dei risultati raggiunti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">In questa maniera cala drasticamente l\u2019assenteismo e incrementa la volont\u00e0 di apprendere. Studi hanno dimostrato che un gruppo cerca sempre di imitare lo stile del <\/span><i><span style=\"font-weight: 400;\">leader servant<\/span><\/i><span style=\"font-weight: 400;\"> e gli esempi positivi che questo trasmette comportano effetti benefici sull\u2019approccio che i dipendenti hanno verso il proprio lavoro.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Con l\u2019intento di creare un buon ambiente lavorativo, i <\/span><i><span style=\"font-weight: 400;\">leader servant <\/span><\/i><span style=\"font-weight: 400;\">caldeggiano la diversit\u00e0 e la tolleranza verso possibili errori, che al contrario possono anche essere visti come possibile fonte di apprendimento.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Ascoltare un dipendente, cercare di capire il suo stato d\u2019animo, viene impiegata come strategia per la risoluzione dei conflitti. Anche il perdono \u00e8 una parte fondamentale per la risoluzione di eventuali divergenze. Tutto questo si riflette in maniera positiva sulle performance lavorative.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00c8 ovvio che un ambiente lavorativo sereno e motivante aiuta la concentrazione e il potenziamento delle competenze individuali e se i dipendenti si sentono pi\u00f9 responsabilizzati aumenteranno il loro grado di partecipazione\u00a0 in tutte le fasi dell\u2019attivit\u00e0.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Grazie al <\/span><b>Corso Essere <\/b><b><i>Manager <\/i><\/b><b>in mondo VUCRA<\/b><span style=\"font-weight: 400;\"> potenzierai le capacit\u00e0 manageriali per sviluppare le <\/span><i><span style=\"font-weight: 400;\">soft skills<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Vuoi scoprirne di pi\u00f9 sull\u2019<a href=\"https:\/\/www.emagister.it\/corsi_make_it-cen-74422.htm\" target=\"_blank\" rel=\"noopener\">offerta formativa<\/a> di <\/span><i><span style=\"font-weight: 400;\">Make it So<\/span><\/i><span style=\"font-weight: 400;\">?<strong><a href=\"https:\/\/www.emagister.it\/contact\" target=\"_blank\" rel=\"noopener\"> Contatta con Emagister<\/a> <\/strong>e ti aiuteremo ad ottenere tutte le informazioni di cui hai bisogno.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ti piacerebbe sapere come far crescere il tuo team e ottenere grandi risultati? Make It So ti mostra come, continua a leggere questo articolo!\u00a0<\/p>\n","protected":false},"author":161,"featured_media":5071,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[260,592,867,954,955],"class_list":["post-5070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-clienti","tag-centri-di-formazione","tag-centri-emagister","tag-noticiasskuola","tag-954","tag-make-it-so"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La &quot;Leadership Servant&quot;, il nuovo modo di essere leader! - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La &quot;Leadership Servant&quot;, il nuovo modo di essere leader! - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"Ti piacerebbe sapere come far crescere il tuo team e ottenere grandi risultati? Make It So ti mostra come, continua a leggere questo articolo!\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-17T08:21:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-17T13:28:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/12\/Leadership-1-kraken.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1212\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Italia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Italia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-leadership-servant-il-nuovo-modo-di-essere-leader\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-leadership-servant-il-nuovo-modo-di-essere-leader\\\/\"},\"author\":{\"name\":\"Redazione Italia\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/6a9d1521294589a00d6bc89c01249ec9\"},\"headline\":\"La &#8220;Leadership Servant&#8221;, il nuovo modo di essere leader!\",\"datePublished\":\"2020-01-17T08:21:13+00:00\",\"dateModified\":\"2020-01-17T13:28:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-leadership-servant-il-nuovo-modo-di-essere-leader\\\/\"},\"wordCount\":659,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-leadership-servant-il-nuovo-modo-di-essere-leader\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Leadership-1-kraken.jpg\",\"keywords\":[\"Centri di Formazione\",\"centri emagister\",\"noticiasSkuola\",\"60753100102569516950705268674568\",\"Make It So\"],\"articleSection\":[\"I Nostri Clienti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-leadership-servant-il-nuovo-modo-di-essere-leader\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-leadership-servant-il-nuovo-modo-di-essere-leader\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-leadership-servant-il-nuovo-modo-di-essere-leader\\\/\",\"name\":\"La \\\"Leadership Servant\\\", il nuovo modo di essere leader! - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-leadership-servant-il-nuovo-modo-di-essere-leader\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-leadership-servant-il-nuovo-modo-di-essere-leader\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Leadership-1-kraken.jpg\",\"datePublished\":\"2020-01-17T08:21:13+00:00\",\"dateModified\":\"2020-01-17T13:28:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-leadership-servant-il-nuovo-modo-di-essere-leader\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-leadership-servant-il-nuovo-modo-di-essere-leader\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-leadership-servant-il-nuovo-modo-di-essere-leader\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Leadership-1-kraken.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Leadership-1-kraken.jpg\",\"width\":1920,\"height\":1212},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-leadership-servant-il-nuovo-modo-di-essere-leader\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Nostri Clienti\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/i-nostri-clienti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La &#8220;Leadership Servant&#8221;, il nuovo modo di essere leader!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/6a9d1521294589a00d6bc89c01249ec9\",\"name\":\"Redazione Italia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"caption\":\"Redazione Italia\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/redazione-italia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La \"Leadership Servant\", il nuovo modo di essere leader! - Emagister Blog Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/","og_locale":"it_IT","og_type":"article","og_title":"La \"Leadership Servant\", il nuovo modo di essere leader! - Emagister Blog Italia","og_description":"Ti piacerebbe sapere come far crescere il tuo team e ottenere grandi risultati? Make It So ti mostra come, continua a leggere questo articolo!\u00a0","og_url":"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2020-01-17T08:21:13+00:00","article_modified_time":"2020-01-17T13:28:32+00:00","og_image":[{"width":1920,"height":1212,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/12\/Leadership-1-kraken.jpg","type":"image\/jpeg"}],"author":"Redazione Italia","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Redazione Italia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/"},"author":{"name":"Redazione Italia","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/6a9d1521294589a00d6bc89c01249ec9"},"headline":"La &#8220;Leadership Servant&#8221;, il nuovo modo di essere leader!","datePublished":"2020-01-17T08:21:13+00:00","dateModified":"2020-01-17T13:28:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/"},"wordCount":659,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/12\/Leadership-1-kraken.jpg","keywords":["Centri di Formazione","centri emagister","noticiasSkuola","60753100102569516950705268674568","Make It So"],"articleSection":["I Nostri Clienti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/","url":"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/","name":"La \"Leadership Servant\", il nuovo modo di essere leader! - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/12\/Leadership-1-kraken.jpg","datePublished":"2020-01-17T08:21:13+00:00","dateModified":"2020-01-17T13:28:32+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/12\/Leadership-1-kraken.jpg","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/12\/Leadership-1-kraken.jpg","width":1920,"height":1212},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/la-leadership-servant-il-nuovo-modo-di-essere-leader\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"I Nostri Clienti","item":"https:\/\/www.emagister.it\/blog\/category\/i-nostri-clienti\/"},{"@type":"ListItem","position":3,"name":"La &#8220;Leadership Servant&#8221;, il nuovo modo di essere leader!"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/6a9d1521294589a00d6bc89c01249ec9","name":"Redazione Italia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","caption":"Redazione Italia"},"url":"https:\/\/www.emagister.it\/blog\/author\/redazione-italia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/5070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/161"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=5070"}],"version-history":[{"count":3,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/5070\/revisions"}],"predecessor-version":[{"id":5188,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/5070\/revisions\/5188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/5071"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=5070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=5070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=5070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}