{"id":5829,"date":"2020-03-24T12:59:58","date_gmt":"2020-03-24T12:59:58","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=5829"},"modified":"2020-03-24T12:59:58","modified_gmt":"2020-03-24T12:59:58","slug":"quando-rivolgersi-a-un-career-coach","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/","title":{"rendered":"Quando rivolgersi a un Career Coach?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Le realt\u00e0 lavorative hanno cambiato in poco tempo i loro connotati, rendendo i<strong> percorsi di carriera sempre meno lineari<\/strong> e unidirezionali, oggi non \u00e8 inconsueto cambiare aziende, settori e perfino ruoli, mettendo in discussione continua il proprio avvenire lavorativo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le cause certo possono essere di vario tipo, possono derivare da<strong> eventi esterni<\/strong> come una riorganizzazione aziendale o un trasferimento, ma possono essere dettate anche da motivazioni personali. La scelta di<strong> cambiare ambiente lavorativo<\/strong> potrebbe essere una possibile risposta per soddisfare desideri e ambizioni e migliorare la propria posizione lavorativa.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ogni tipo di cambiamento porta con s\u00e9 delle <strong>conseguenze anche molto radicali<\/strong> nella vita personale e lavorativa delle persone, coinvolgendo sia la sfera privata e familiare\u00a0 che la vita \u201csociale\u201d e professionale. Non \u00e8 necessario pensare a grandi stravolgimenti delle nostre vite, anche delle piccole modifiche della nostra routine quotidiana possono avere delle <strong>conseguenze meno evidenti<\/strong> ma che a lungo andare terminano per avere un impatto diretto sulle nostre vite. Un esempio pu\u00f2 essere un crescente sentimento di<strong> insoddisfazione legato alla nostra posizione aziendale<\/strong>, che pu\u00f2 indurci ad assumere la scelta drastica di dare una svolta radicale alla nostra carriera cercando un nuovo impiego.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">In tutte queste occasioni il rischio di perdere di vista i nostri obiettivi diventa molto concreto e potrebbe generare sconforto e confusione. In queste situazioni il <a href=\"https:\/\/www.emagister.it\/corso_assessment_center_e_valutazione_del_potenziale-ec2780202.htm\" target=\"_blank\" rel=\"noopener\"><strong>Career<\/strong> <strong>Counselor<\/strong> <\/a>diviene una figura chiave in grado di aiutarci a\u00a0 riflettere sulle proprie competenze, su ci\u00f2 che desidera realmente, sui valori e sulle motivazioni che la orientano nelle scelte, per far s\u00ec che il nuovo cammino sia quanto pi\u00f9 vicino possibile al proprio essere, sia in termini di <strong>competenze<\/strong>\u00a0che di abilit\u00e0.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La <strong>consulenza di carriera<\/strong> \u00e8 uno strumento molto utile che si avvale di tecniche diverse per poter condurre la persona a una<strong> maggiore consapevolezza delle proprie potenzialit\u00e0<\/strong>, ma anche dei propri limiti, tracciando un percorso professionale improntato sulla valorizzazione delle proprie abilit\u00e0 specifiche. Gli incontri con il counselor si dividono in due momenti: la prima parte pone maggiore focus sulle <strong>esperienze pregresse<\/strong>, soffermandosi in particolare sui <strong>percorsi<\/strong> <strong>scolastici<\/strong> spesso sottovalutati o giudicati con eccessiva superficialit\u00e0. Ripercorrere le tappe del passato con lo sguardo del presente, in parte rivolto al futuro, consente di acquisire maggiore consapevolezza di s\u00e9, generando un cambio nel punto di vista da cui si osserva la <strong>propria vita professionale<\/strong>.<a href=\"https:\/\/www.emagister.it\/corsi_make_it-cen-74422.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-4585 size-full\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/11\/Make-It-So.png\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/span><\/p>\n<p><span style=\"font-weight: 400;\">La figura del<strong> career counselor<\/strong> permette di orientare questo sguardo in una prospettiva introspettiva, lasciando la parte dell\u2019azione e della progettualit\u00e0 ad un secondo momento. La differenza \u00e8 proprio in questo punto, molto spesso siamo portati a sottovalutare l<strong>\u2019importanza dell\u2019analisi<\/strong>, concentrando tutti i nostri sforzi nell\u2019azione: qualsiasi viaggio intrapreso senza il giusto equipaggiamento avr\u00e0 maggiori probabilit\u00e0 di non essere portato a termine o, peggio ancora, risultare insoddisfacente. Intraprenderlo con l\u2019aiuto di un consulente di carriera, significa avere il giusto <strong>punto di riferimento<\/strong> per trasformare una pausa forzata in un momento per ripartire al meglio o per fare chiarezza in un periodo di confusione.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Solo dopo aver concluso un\u2019accurata analisi delle proprie competenze, abilit\u00e0 e potenzialit\u00e0, e dopo aver esplorato le proprie spinte motivazionali, i bisogni e i valori, ci si dedica al<strong> piano d\u2019azione.<\/strong> In questa seconda fase la consulenza di carriera si concentra soprattutto nell\u2019analisi dei fattori esterni che possono influire sul percorso: mercato del lavoro, opportunit\u00e0 concrete per la persona in termini di settori, ruoli professionali e incentivi all&#8217;assunzione o <strong>all\u2019autoimprenditorialit\u00e0<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Grazie agli elementi di consapevolezza emersi precedentemente sar\u00e0 possibile tradurre il lavoro introspettivo svolto precedentemente in obiettivi concreti e azioni mirati a realizzarli. Rimane chiave anche in questo momento la figura del counselor in quanto permette di <strong>mantenere alta la motivazione,<\/strong> permettendo alla persona di fronteggiare eventuali ostacoli con sicurezza e serenit\u00e0, supportandola nell<strong>\u2019identificare le risorse<\/strong> di cui dispone per superarli.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Alla luce di quanto detto finora appare chiaro come la figura del Career Counselor divenga un utile supporto per affrontare <strong>momenti di cambiamento, difficolt\u00e0 e trasformazione.<\/strong> Un esempio pratico pu\u00f2 essere ad esempio la perdita del lavoro, un momento delicato in cui \u00e8 necessario disporre di grande sicurezza e consapevolezza delle proprie capacit\u00e0 per poter ripartire da zero nella realizzazione di s\u00e9, <strong>elemento<\/strong> <strong>imprescindibile<\/strong> per coloro che stanno lavorando ma non si sentono soddisfatti della propria vita professionale.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se sei curioso di conoscere tutte le potenzialit\u00e0 offerte dalla consulenza di carriera, il centro <a href=\"https:\/\/www.emagister.it\/corsi_make_it-cen-74422.htm\" target=\"_blank\" rel=\"noopener\">Make it so<\/a>, propone incontri personalizzati con Massimo Perciavalle, Career Coach, <\/span><b>accreditato e certificato PCC <\/b><span style=\"font-weight: 400;\">ti supporter\u00e0 a 360\u00b0 e ti aiuta a sviluppare le tue soft skills e muoversi autonomamente nel mercato del lavoro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hai gi\u00e0 effettuato degli incontri con un Career Coach, facci sapere com&#8217;\u00e8 andata e cosa ne pensi lasciando la tua <a href=\"https:\/\/www.emagister.it\/reviews\/add\" target=\"_blank\" rel=\"noopener\"><strong>opinione<\/strong> <\/a>su Emagister.it, in questo modo potrai aiutare tanti altri utenti a scegliere la<strong> formazione adatta<\/strong> alle loro necessit\u00e0.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le realt\u00e0 lavorative hanno cambiato in poco tempo i loro connotati, rendendo i percorsi di carriera sempre meno lineari e unidirezionali, oggi non \u00e8 inconsueto cambiare aziende, settori e perfino ruoli, mettendo in discussione continua il proprio avvenire lavorativo. Le cause certo possono essere di vario tipo, possono derivare da eventi esterni come una riorganizzazione [&hellip;]<\/p>\n","protected":false},"author":161,"featured_media":4947,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[260,592,867,954,955],"class_list":["post-5829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-clienti","tag-centri-di-formazione","tag-centri-emagister","tag-noticiasskuola","tag-954","tag-make-it-so"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quando rivolgersi a un Career Coach? - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quando rivolgersi a un Career Coach? - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"Le realt\u00e0 lavorative hanno cambiato in poco tempo i loro connotati, rendendo i percorsi di carriera sempre meno lineari e unidirezionali, oggi non \u00e8 inconsueto cambiare aziende, settori e perfino ruoli, mettendo in discussione continua il proprio avvenire lavorativo. Le cause certo possono essere di vario tipo, possono derivare da eventi esterni come una riorganizzazione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-24T12:59:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/12\/Trova-la-grinta-per-sfondare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1242\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Italia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Italia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/quando-rivolgersi-a-un-career-coach\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/quando-rivolgersi-a-un-career-coach\\\/\"},\"author\":{\"name\":\"Redazione Italia\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/6a9d1521294589a00d6bc89c01249ec9\"},\"headline\":\"Quando rivolgersi a un Career Coach?\",\"datePublished\":\"2020-03-24T12:59:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/quando-rivolgersi-a-un-career-coach\\\/\"},\"wordCount\":797,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/quando-rivolgersi-a-un-career-coach\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Trova-la-grinta-per-sfondare.jpg\",\"keywords\":[\"Centri di Formazione\",\"centri emagister\",\"noticiasSkuola\",\"60753100102569516950705268674568\",\"Make It So\"],\"articleSection\":[\"I Nostri Clienti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/quando-rivolgersi-a-un-career-coach\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/quando-rivolgersi-a-un-career-coach\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/quando-rivolgersi-a-un-career-coach\\\/\",\"name\":\"Quando rivolgersi a un Career Coach? - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/quando-rivolgersi-a-un-career-coach\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/quando-rivolgersi-a-un-career-coach\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Trova-la-grinta-per-sfondare.jpg\",\"datePublished\":\"2020-03-24T12:59:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/quando-rivolgersi-a-un-career-coach\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/quando-rivolgersi-a-un-career-coach\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/quando-rivolgersi-a-un-career-coach\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Trova-la-grinta-per-sfondare.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Trova-la-grinta-per-sfondare.jpg\",\"width\":1920,\"height\":1242},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/quando-rivolgersi-a-un-career-coach\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Nostri Clienti\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/i-nostri-clienti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quando rivolgersi a un Career Coach?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/6a9d1521294589a00d6bc89c01249ec9\",\"name\":\"Redazione Italia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"caption\":\"Redazione Italia\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/redazione-italia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quando rivolgersi a un Career Coach? - Emagister Blog Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/","og_locale":"it_IT","og_type":"article","og_title":"Quando rivolgersi a un Career Coach? - Emagister Blog Italia","og_description":"Le realt\u00e0 lavorative hanno cambiato in poco tempo i loro connotati, rendendo i percorsi di carriera sempre meno lineari e unidirezionali, oggi non \u00e8 inconsueto cambiare aziende, settori e perfino ruoli, mettendo in discussione continua il proprio avvenire lavorativo. Le cause certo possono essere di vario tipo, possono derivare da eventi esterni come una riorganizzazione [&hellip;]","og_url":"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2020-03-24T12:59:58+00:00","og_image":[{"width":1920,"height":1242,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/12\/Trova-la-grinta-per-sfondare.jpg","type":"image\/jpeg"}],"author":"Redazione Italia","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Redazione Italia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/"},"author":{"name":"Redazione Italia","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/6a9d1521294589a00d6bc89c01249ec9"},"headline":"Quando rivolgersi a un Career Coach?","datePublished":"2020-03-24T12:59:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/"},"wordCount":797,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/12\/Trova-la-grinta-per-sfondare.jpg","keywords":["Centri di Formazione","centri emagister","noticiasSkuola","60753100102569516950705268674568","Make It So"],"articleSection":["I Nostri Clienti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/","url":"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/","name":"Quando rivolgersi a un Career Coach? - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/12\/Trova-la-grinta-per-sfondare.jpg","datePublished":"2020-03-24T12:59:58+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/12\/Trova-la-grinta-per-sfondare.jpg","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/12\/Trova-la-grinta-per-sfondare.jpg","width":1920,"height":1242},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/quando-rivolgersi-a-un-career-coach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"I Nostri Clienti","item":"https:\/\/www.emagister.it\/blog\/category\/i-nostri-clienti\/"},{"@type":"ListItem","position":3,"name":"Quando rivolgersi a un Career Coach?"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/6a9d1521294589a00d6bc89c01249ec9","name":"Redazione Italia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","caption":"Redazione Italia"},"url":"https:\/\/www.emagister.it\/blog\/author\/redazione-italia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/5829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/161"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=5829"}],"version-history":[{"count":1,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/5829\/revisions"}],"predecessor-version":[{"id":5830,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/5829\/revisions\/5830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/4947"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=5829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=5829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=5829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}