{"id":6345,"date":"2020-06-12T08:50:10","date_gmt":"2020-06-12T08:50:10","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=6345"},"modified":"2020-06-12T08:50:10","modified_gmt":"2020-06-12T08:50:10","slug":"come-far-avanzare-la-propria-carriera-professionale","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/","title":{"rendered":"Come far avanzare la propria carriera professionale?"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Se sei tra le migliaia di persone che sono alla ricerca di un impiego dopo il lockdown conosci molto bene le difficolt\u00e0 che sta attraversando il <strong>mercato del lavoro<\/strong> in questo momento. La crisi sanitaria senza precedenti a cui abbiamo assistito ha innescato una crisi economica che ha paralizzato il Paese per alcuni mesi, rendendo ancora pi\u00f9 difficile avviare la propria carriera professionale.\u00a0<\/span><!--more--><\/p>\n<p><span style=\"font-weight: 400\">Sebbene lo scenario descritto non sia dei pi\u00f9 rosei \u00e8 importante non arrendersi e cercare in ogni modo di creare le opportunit\u00e0 giuste per poter<strong> potenziare le proprie abilit\u00e0<\/strong>. Tutte le crisi rappresentano infatti non solo un momento di difficolt\u00e0, ma anche una buona occasione per poter guardare con occhio pi\u00f9 critico la propria<strong> figura professionale<\/strong>, <\/span><b>s<\/b><b>coprire le proprie potenzialit\u00e0<\/b><span style=\"font-weight: 400\"> e finalmente riuscire nel mondo del lavoro. Ma da dove iniziare?<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Mettersi sempre in gioco<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Potr\u00e0 sembrare banale, ma in realt\u00e0 \u00e8 la prima regola da non dimenticare mai: lanciarsi a capofitto in ogni occasione che ci si presenta. Non ci si pu\u00f2 aspettare che il proprio talento e le <\/span><b>proprie potenzialit\u00e0<\/b><span style=\"font-weight: 400\"> emergano sempre spontaneamente.<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><span style=\"font-weight: 400\">Attenzione per\u00f2 a non confondere lo <strong>spirito di iniziativa<\/strong> con l\u2019approssimazione, prepara in ogni minimo dettaglio il tuo colloquio, studia la storia dell\u2019azienda per cui lavorerai, metti in risalto i tuoi punti forti e sii onesto riguardo alle tue criticit\u00e0. <\/span><b>Mai fermarsi<\/b><span style=\"font-weight: 400\"> al solo studio quindi, ma cercare \u201cdi sporcarsi le mani\u201d il pi\u00f9 possibile, cos\u00ec da iniziare a fare esperienza.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Impegnarsi al massimo<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Sei riuscito nel tuo intento, hai <\/span><b>trovato il lavoro adatto alle tue capacit\u00e0<\/b><span style=\"font-weight: 400\">, e ora cosa fare? L\u2019unica scelta vincente \u00e8 l\u2019impegno, buttati a capofitto nella tua nuova mansione. Pensa all\u2019ambiente professionale come una lunga scalinata, i primi gradini potrebbero spaventarti e la scalata potrebbe apparirti un\u2019impresa impossibile. Ma con la giusta perseveranza e impegno riuscirai a scalare un gradino dopo l\u2019altro e<strong> raggiungere finalmente il successo<\/strong>. La <\/span><b>forza di volont\u00e0<\/b><span style=\"font-weight: 400\"> deve essere l\u2019arma in pi\u00f9 per riuscire a sfruttare al massimo le proprie qualit\u00e0; solo cos\u00ec sar\u00e0 possibile coronare i propri sogni.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Avere pazienza e perseveranza<\/span><\/h2>\n<p><b>Costanza, perseveranza e pazienza<\/b><span style=\"font-weight: 400\">, le tre chiavi di volta attorno cui costruire la tua carriera professionale. Queste tre qualit\u00e0 dovrebbero accompagnare ognuno di noi nella propria vita lavorativa, in particolar modo se ci si trova all\u2019inizio di un percorso nel quale bisogna formarsi ed emergere.\u00a0 L\u2019errore pi\u00f9 grande che si possa commettere \u00e8 pensare che il successo possa arrivare improvvisamente <\/span><b>da un giorno all\u2019altro<\/b><span style=\"font-weight: 400\">. Si tratta piuttosto di un percorso lungo e a volte tortuoso, non perdere mai di vista il tuo obiettivo primario, quello di diventare un professionista preparato. Ogni volta che senti di aver raggiunto un traguardo, festeggia la tua vittoria e poi <\/span><b>alza l\u2019asticella<\/b><span style=\"font-weight: 400\"> e punta pi\u00f9 in alto, senza fermarsi mai, sebbene sia importante avere <\/span><b>aspirazioni realistiche<\/b><span style=\"font-weight: 400\">. Per questa ragione, \u00e8 bene fare un\u2019analisi razionale di tanto in tanto e comprendere quali sono gli obiettivi che si possono raggiungere. Con la giusta pazienza sar\u00e0 possibile <\/span><b>raggiungere tanti traguardi<\/b><span style=\"font-weight: 400\"> e superare anche quelle che possono essere delusioni o piccole sconfitte.<a href=\"https:\/\/www.emagister.it\/corsi_centro_europeo_di_formazione_cef-cen-58031.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-4290 size-full\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/10\/CEF.jpg\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/span><\/p>\n<h2><span style=\"font-weight: 400\">I limiti? Non esistono<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Non porre un freno alle tue aspirazioni e ai tuoi sogni! Sembra in contraddizione con quanto scritto sopra, ma non porsi limiti \u00e8 fondamentale per <\/span><b>spiccare il volo<\/b><span style=\"font-weight: 400\">. Il proprio talento emerge poco alla volta, nessuno conosce le proprie potenzialit\u00e0 prima di mettersi in gioco. Spesso, un po\u2019 perch\u00e9 intimoriti da un fallimento o da una delusione, oppure per scarsa autostima, moltissimi preferiscono non <\/span><b>rischiare<\/b><span style=\"font-weight: 400\"> e rimanere nella propria comfort zone, abdicando quindi a qualsiasi <\/span><b>possibilit\u00e0 di successo professionale<\/b><span style=\"font-weight: 400\">. Questo atteggiamento non solo \u00e8 controproducente, ma rischia di minare la nostra autostima, quindi \u00e8 necessario continuare a lavorare puntando sempre al massimo.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Raggiungere il successo non \u00e8 un\u2019utopia<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Non dimenticare mai che raggiungere il successo \u00e8 un&#8217;impresa ardua, ma non impossibile. Per riuscire nel tuo intento tieni sempre a menti i suggerimenti indicati sopra. Con la giusta motivazione, le capacit\u00e0 e perch\u00e9 no?! un pizzico di fortuna, potrai arrivare a raggiungere senza problemi la meta che ti eri prefissato. Per avere qualche chance in pi\u00f9 e conoscere ancora meglio come sfruttare le proprie potenzialit\u00e0, \u00e8 possibile frequentare <\/span><b>corsi professionali online<\/b><span style=\"font-weight: 400\"> come i Corsi CEF. In questo modo sar\u00e0 possibile apprendere gli strumenti necessari per emergere nel mondo del lavoro e <\/span><b>costruire la carriera dei propri sogni<\/b><span style=\"font-weight: 400\"> non sar\u00e0 solo una fantasia.<\/span><\/p>\n<p>Hai gi\u00e0 frequentato un corso di coaching professionale? Facci sapere la tua\u00a0<a href=\"https:\/\/www.emagister.it\/reviews\/add\" target=\"_blank\" rel=\"noopener\">opinione<\/a>\u00a0e potrai partecipare all\u2019estrazione di un buono formazione del valore di 3.000 \u20ac.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se sei tra le migliaia di persone che sono alla ricerca di un impiego dopo il lockdown conosci molto bene le difficolt\u00e0 che sta attraversando il mercato del lavoro in questo momento. La crisi sanitaria senza precedenti a cui abbiamo assistito ha innescato una crisi economica che ha paralizzato il Paese per alcuni mesi, rendendo [&hellip;]<\/p>\n","protected":false},"author":161,"featured_media":5317,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[260,592,923,924,1037],"class_list":["post-6345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-clienti","tag-centri-di-formazione","tag-centri-emagister","tag-923","tag-centro-europeo-di-formazione-cef","tag-ij_sector_center_50659050082349536565505351654569_18"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come far avanzare la propria carriera professionale? - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come far avanzare la propria carriera professionale? - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"Se sei tra le migliaia di persone che sono alla ricerca di un impiego dopo il lockdown conosci molto bene le difficolt\u00e0 che sta attraversando il mercato del lavoro in questo momento. La crisi sanitaria senza precedenti a cui abbiamo assistito ha innescato una crisi economica che ha paralizzato il Paese per alcuni mesi, rendendo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-12T08:50:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2020\/01\/LEADERSHIP-KRAKEN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Italia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Italia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-far-avanzare-la-propria-carriera-professionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-far-avanzare-la-propria-carriera-professionale\\\/\"},\"author\":{\"name\":\"Redazione Italia\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/6a9d1521294589a00d6bc89c01249ec9\"},\"headline\":\"Come far avanzare la propria carriera professionale?\",\"datePublished\":\"2020-06-12T08:50:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-far-avanzare-la-propria-carriera-professionale\\\/\"},\"wordCount\":754,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-far-avanzare-la-propria-carriera-professionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/LEADERSHIP-KRAKEN.jpg\",\"keywords\":[\"Centri di Formazione\",\"centri emagister\",\"50659050082349536565505351654569\",\"Centro Europeo di Formazione - CEF\",\"ij_sector_center_50659050082349536565505351654569_18\"],\"articleSection\":[\"I Nostri Clienti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-far-avanzare-la-propria-carriera-professionale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-far-avanzare-la-propria-carriera-professionale\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-far-avanzare-la-propria-carriera-professionale\\\/\",\"name\":\"Come far avanzare la propria carriera professionale? - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-far-avanzare-la-propria-carriera-professionale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-far-avanzare-la-propria-carriera-professionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/LEADERSHIP-KRAKEN.jpg\",\"datePublished\":\"2020-06-12T08:50:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-far-avanzare-la-propria-carriera-professionale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-far-avanzare-la-propria-carriera-professionale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-far-avanzare-la-propria-carriera-professionale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/LEADERSHIP-KRAKEN.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/LEADERSHIP-KRAKEN.jpg\",\"width\":1920,\"height\":1274},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/come-far-avanzare-la-propria-carriera-professionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Nostri Clienti\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/i-nostri-clienti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Come far avanzare la propria carriera professionale?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/6a9d1521294589a00d6bc89c01249ec9\",\"name\":\"Redazione Italia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"caption\":\"Redazione Italia\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/redazione-italia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come far avanzare la propria carriera professionale? - Emagister Blog Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/","og_locale":"it_IT","og_type":"article","og_title":"Come far avanzare la propria carriera professionale? - Emagister Blog Italia","og_description":"Se sei tra le migliaia di persone che sono alla ricerca di un impiego dopo il lockdown conosci molto bene le difficolt\u00e0 che sta attraversando il mercato del lavoro in questo momento. La crisi sanitaria senza precedenti a cui abbiamo assistito ha innescato una crisi economica che ha paralizzato il Paese per alcuni mesi, rendendo [&hellip;]","og_url":"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2020-06-12T08:50:10+00:00","og_image":[{"width":1920,"height":1274,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2020\/01\/LEADERSHIP-KRAKEN.jpg","type":"image\/jpeg"}],"author":"Redazione Italia","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Redazione Italia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/"},"author":{"name":"Redazione Italia","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/6a9d1521294589a00d6bc89c01249ec9"},"headline":"Come far avanzare la propria carriera professionale?","datePublished":"2020-06-12T08:50:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/"},"wordCount":754,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2020\/01\/LEADERSHIP-KRAKEN.jpg","keywords":["Centri di Formazione","centri emagister","50659050082349536565505351654569","Centro Europeo di Formazione - CEF","ij_sector_center_50659050082349536565505351654569_18"],"articleSection":["I Nostri Clienti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/","url":"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/","name":"Come far avanzare la propria carriera professionale? - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2020\/01\/LEADERSHIP-KRAKEN.jpg","datePublished":"2020-06-12T08:50:10+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2020\/01\/LEADERSHIP-KRAKEN.jpg","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2020\/01\/LEADERSHIP-KRAKEN.jpg","width":1920,"height":1274},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/come-far-avanzare-la-propria-carriera-professionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"I Nostri Clienti","item":"https:\/\/www.emagister.it\/blog\/category\/i-nostri-clienti\/"},{"@type":"ListItem","position":3,"name":"Come far avanzare la propria carriera professionale?"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/6a9d1521294589a00d6bc89c01249ec9","name":"Redazione Italia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","caption":"Redazione Italia"},"url":"https:\/\/www.emagister.it\/blog\/author\/redazione-italia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/6345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/161"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=6345"}],"version-history":[{"count":2,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/6345\/revisions"}],"predecessor-version":[{"id":6347,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/6345\/revisions\/6347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/5317"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=6345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=6345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=6345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}