{"id":6590,"date":"2020-07-21T15:57:13","date_gmt":"2020-07-21T15:57:13","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=6590"},"modified":"2020-07-21T15:57:13","modified_gmt":"2020-07-21T15:57:13","slug":"il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/","title":{"rendered":"Il parto a domicilio, quando la tradizione diventa avanguardia"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Sono sempre di pi\u00f9 le donne che scelgono di vivere il proprio parto in un ambiente familiare, lontano dai luoghi asettici di una stanza d\u2019ospedale. Il <strong>parto extra ospedaliero,<\/strong> a domicilio o in casa Maternit\u00e0 \u00e8 una realt\u00e0 sempre pi\u00f9 presente in Italia, UniCamillus ha affrontato il tema durante un webinar tenuto da ostetriche libero-professioniste per le\/gli studenti del Corso di Laurea in Ostetricia.\u00a0<\/span><!--more--><\/p>\n<p><span style=\"font-weight: 400\">Questo incontro ha dato modo agli studenti di entrare a contatto con un modo diverso di vivere il momento del parto, confrontandosi con i vantaggi e le criticit\u00e1 della scelta di un percorso di nascita extra-ospedaliero. Il webinar intitolato \u201c<\/span><b>Il parto extra-ospedaliero: a domicilio e in Casa Maternit\u00e0<\/b><span style=\"font-weight: 400\">\u201d \u00e8 stato tenuto dalle ostetriche della Casa Maternit\u00e0 \u201cNascere e Crescere\u201d di Roma, di cui la Dott.ssa Anna Maria Gioacchini \u00e8 la responsabile.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Per UniCamillus l\u2019incontro ha rappresentato un momento di confronto arricchente che ha fornito agli studenti strumenti teorici e pratici per imparare come offrire un<strong>\u2019assistenza alla nascita rispettosa dei ritmi e delle modalit\u00e0 di ciascun travaglio.<a href=\"https:\/\/www.emagister.it\/corsi_unicamillus_international_medical_university-cen-106220.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-6542 size-medium\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2020\/07\/descarga-1-300x160.png\" alt=\"\" width=\"300\" height=\"160\" \/><\/a><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400\">Grazie a questo primo momento di condivisione online \u00e8 nata l\u2019idea di proseguire il progetto con una serie di incontri che si terranno anche durante il prossimo anno accademico. N<\/span>asce cos\u00ec una nuova sinergia tra UniCamillus e <strong>la rete delle ostetriche libero-professioniste di Roma e del Lazio<\/strong><span style=\"font-weight: 400\">. Lo scopo \u00e8 quello di sensibilizzare la nuova classe di professionisti sanitari alla consapevolezza che la<strong> figura professionale dell\u2019ostetrica<\/strong> pu\u00f2 sostenere e assistere le future mamme anche senza la necessaria presenza delle strutture sanitarie, operando in un contesto di libera professione attraverso l\u2019assistenza a domicilio.\u00a0<\/span><\/p>\n<p>Vuoi conoscere nel dettaglio tutto il catalogo Unicamillus? Mettiti in\u00a0<a href=\"https:\/\/www.emagister.it\/contact\/student\" target=\"_blank\" rel=\"noopener\">contatto<\/a>\u00a0con lo staff Emagister, sapremo consigliarti il corso pi\u00f9 adatto alle tue esigenze professionali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono sempre di pi\u00f9 le donne che scelgono di vivere il proprio parto in un ambiente familiare, lontano dai luoghi asettici di una stanza d\u2019ospedale. Il parto extra ospedaliero, a domicilio o in casa Maternit\u00e0 \u00e8 una realt\u00e0 sempre pi\u00f9 presente in Italia, UniCamillus ha affrontato il tema durante un webinar tenuto da ostetriche libero-professioniste [&hellip;]<\/p>\n","protected":false},"author":161,"featured_media":6591,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[260,592,867,1061,1062],"class_list":["post-6590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-clienti","tag-centri-di-formazione","tag-centri-emagister","tag-noticiasskuola","tag-unicamillus-international-medical-university","tag-1062"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il parto a domicilio, quando la tradizione diventa avanguardia - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il parto a domicilio, quando la tradizione diventa avanguardia - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"Sono sempre di pi\u00f9 le donne che scelgono di vivere il proprio parto in un ambiente familiare, lontano dai luoghi asettici di una stanza d\u2019ospedale. Il parto extra ospedaliero, a domicilio o in casa Maternit\u00e0 \u00e8 una realt\u00e0 sempre pi\u00f9 presente in Italia, UniCamillus ha affrontato il tema durante un webinar tenuto da ostetriche libero-professioniste [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-21T15:57:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2020\/07\/freestocks-ux53SGpRAHU-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Italia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Italia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\\\/\"},\"author\":{\"name\":\"Redazione Italia\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/6a9d1521294589a00d6bc89c01249ec9\"},\"headline\":\"Il parto a domicilio, quando la tradizione diventa avanguardia\",\"datePublished\":\"2020-07-21T15:57:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\\\/\"},\"wordCount\":299,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/freestocks-ux53SGpRAHU-unsplash.jpg\",\"keywords\":[\"Centri di Formazione\",\"centri emagister\",\"noticiasSkuola\",\"UniCamillus \u2013 International Medical University\",\"99992269674249392522766775092644\"],\"articleSection\":[\"I Nostri Clienti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\\\/\",\"name\":\"Il parto a domicilio, quando la tradizione diventa avanguardia - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/freestocks-ux53SGpRAHU-unsplash.jpg\",\"datePublished\":\"2020-07-21T15:57:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/freestocks-ux53SGpRAHU-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/freestocks-ux53SGpRAHU-unsplash.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Nostri Clienti\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/i-nostri-clienti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il parto a domicilio, quando la tradizione diventa avanguardia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/6a9d1521294589a00d6bc89c01249ec9\",\"name\":\"Redazione Italia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"caption\":\"Redazione Italia\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/redazione-italia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il parto a domicilio, quando la tradizione diventa avanguardia - Emagister Blog Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/","og_locale":"it_IT","og_type":"article","og_title":"Il parto a domicilio, quando la tradizione diventa avanguardia - Emagister Blog Italia","og_description":"Sono sempre di pi\u00f9 le donne che scelgono di vivere il proprio parto in un ambiente familiare, lontano dai luoghi asettici di una stanza d\u2019ospedale. Il parto extra ospedaliero, a domicilio o in casa Maternit\u00e0 \u00e8 una realt\u00e0 sempre pi\u00f9 presente in Italia, UniCamillus ha affrontato il tema durante un webinar tenuto da ostetriche libero-professioniste [&hellip;]","og_url":"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2020-07-21T15:57:13+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2020\/07\/freestocks-ux53SGpRAHU-unsplash.jpg","type":"image\/jpeg"}],"author":"Redazione Italia","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Redazione Italia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/"},"author":{"name":"Redazione Italia","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/6a9d1521294589a00d6bc89c01249ec9"},"headline":"Il parto a domicilio, quando la tradizione diventa avanguardia","datePublished":"2020-07-21T15:57:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/"},"wordCount":299,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2020\/07\/freestocks-ux53SGpRAHU-unsplash.jpg","keywords":["Centri di Formazione","centri emagister","noticiasSkuola","UniCamillus \u2013 International Medical University","99992269674249392522766775092644"],"articleSection":["I Nostri Clienti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/","url":"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/","name":"Il parto a domicilio, quando la tradizione diventa avanguardia - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2020\/07\/freestocks-ux53SGpRAHU-unsplash.jpg","datePublished":"2020-07-21T15:57:13+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2020\/07\/freestocks-ux53SGpRAHU-unsplash.jpg","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2020\/07\/freestocks-ux53SGpRAHU-unsplash.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/il-parto-a-domicilio-quando-la-tradizione-diventa-avanguardia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"I Nostri Clienti","item":"https:\/\/www.emagister.it\/blog\/category\/i-nostri-clienti\/"},{"@type":"ListItem","position":3,"name":"Il parto a domicilio, quando la tradizione diventa avanguardia"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/6a9d1521294589a00d6bc89c01249ec9","name":"Redazione Italia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","caption":"Redazione Italia"},"url":"https:\/\/www.emagister.it\/blog\/author\/redazione-italia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/6590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/161"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=6590"}],"version-history":[{"count":2,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/6590\/revisions"}],"predecessor-version":[{"id":6593,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/6590\/revisions\/6593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/6591"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=6590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=6590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=6590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}