{"id":7688,"date":"2021-03-10T09:12:42","date_gmt":"2021-03-10T09:12:42","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=7688"},"modified":"2021-04-01T10:00:36","modified_gmt":"2021-04-01T10:00:36","slug":"la-dieta-chetogenica-i-benefici-oltre-il-trend","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/","title":{"rendered":"La dieta chetogenica, i benefici oltre il trend"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Sono ormai diversi anni che si sente parlare sempre pi\u00f9 spesso della\u00a0<\/span><b>dieta chetogenica<\/b><span style=\"font-weight: 400;\">, un programma nutrizionale che purtroppo troppo spesso viene operato in maniera ingiustificatamente estrema. Si tratta di diete ferree a base di sole proteine, con calorie molto basse e soprattutto proposta da chi non solo non dovrebbe o potrebbe farlo, ma che non ha le conoscenze per caratterizzarla.<\/span><!--more--><\/p>\n<p><span style=\"font-weight: 400;\">Una diceria che purtroppo banalizza molto i processi che sono alla base di questo tipo di alimentazione, dicono che basta assumere meno di 30 grammi di carboidrati al giorno per avere la\u00a0<\/span><b>chetosi.\u00a0<\/b><span style=\"font-weight: 400;\">Il concetto \u00e8 per lo pi\u00f9 corretto ma non basta n\u00e9 per assicurare il risultato sperato, n\u00e9 per garantire che, specialmente a lungo termine, questo programma non provochi dei problemi, a volte anche gravi.<\/span><\/p>\n<h2><b>Affidarsi a un professionista, sempre!<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Come per tutti i programmi alimentare, anche la\u00a0<\/span><b>dieta chetogenica<\/b><span style=\"font-weight: 400;\">\u00a0andrebbe operata sempre sotto il controllo di uno specialista, nella fattispecie, un dietologo, un nutrizionista o un dietista e nessun altro. I risultati delle diete fai da te spesso possono portare a dei disequilibri dell&#8217;organismo che possono sfociare in gravi patologie.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Assicurati sempre di rivolgerti a un professionista con un\u2019esperienza nell\u2019operare tale regime,\u00a0 sostituire qualche pasto con una bustina o seguire un pomeriggio di lezione non trasforma nessuno in esperto di\u00a0<\/span><b>dieta chetogenica.<a href=\"https:\/\/www.emagister.it\/corsi_edi_ermes_srl-cen-58066.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-7315 size-full\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2020\/12\/m.png\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/b><\/p>\n<h2><b>Lo studio e i risultati<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Un&#8217;attivit\u00e0 di ricerca condotta dal dottor Roberto Cannataro insieme ad un un team di professionisti, due universit\u00e0 italiane, un spinoff universitario e il supporto di un\u2019azienda che produce dei prodotti appositamente studiati per la\u00a0<\/span><b>dieta chetogenica, ha evidenziato gli effetti benefici di questo tipo di programma.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Campione utilizzato: 36 persone<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Risultati:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">la dieta \u00e8 efficace\u00a0 in ottica dimagrimento<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">le diminuzioni di peso arrivano ad almeno 8kg in 6 settimane<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">la composizione corporea \u00e8 in netto miglioramento nello specifico per quanto riguardano i profili lipidici, glicemici ed insulinici.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">non ci sono state variazioni di rilievo nella funzionalit\u00e0 della tiroide (che troppo spesso viene messa a rischio da regimi troppo restrittivi), del fegato e dei reni.<\/span><\/li>\n<\/ul>\n<p><b>Peculiarit\u00e0 unica di questo studio<\/b><span style=\"font-weight: 400;\">\u00a0\u00e8 stata la valutazione dei\u00a0<\/span><b>miRNA<\/b><span style=\"font-weight: 400;\">\u00a0circolanti, molecole capaci di regolare la sintesi proteica.\u00a0<\/span><span style=\"font-weight: 400;\">Da quest\u2019analisi \u00e8 emerso un\u00a0<\/span><b>imponente effetto antiinfiammatorio<\/b><span style=\"font-weight: 400;\">, regolatore posto sui metabolismi energetici e di omeoastisi dell\u2019osso, persino una regolazione positiva sui geni oncostatici.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dunque, se operata in maniera scientifica, la\u00a0<\/span><b>dieta chetogenica<\/b><span style=\"font-weight: 400;\">\u00a0risulta sicura ed efficace utilizzando un giusto connubio tra cibo ed alimenti sviluppati ad hoc.\u00a0<\/span><span style=\"font-weight: 400;\">La personalizzazione \u00e8 fondamentale per ottenere il risultato e per stabilire\u00a0 un\u2019ottima compliance che ha permesso al 100% dei\u00a0 soggetti di seguire il programma senza abbandonarlo.<\/span><\/p>\n<p>Vuoi ricevere maggiori informazioni su corsi di formazione di Edi.Ermes Academy? Mettiti in\u00a0<a href=\"https:\/\/www.emagister.it\/contact\/student\" target=\"_blank\" rel=\"noopener\">contatto<\/a>\u00a0con lo staff Emagister, sapremo consigliarti il corso pi\u00f9 adatto alle tue esigenze professionali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono ormai diversi anni che si sente parlare sempre pi\u00f9 spesso della\u00a0dieta chetogenica, un programma nutrizionale che purtroppo troppo spesso viene operato in maniera ingiustificatamente estrema. Si tratta di diete ferree a base di sole proteine, con calorie molto basse e soprattutto proposta da chi non solo non dovrebbe o potrebbe farlo, ma che non [&hellip;]<\/p>\n","protected":false},"author":161,"featured_media":7689,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[260,592,867,1097,1098],"class_list":["post-7688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-clienti","tag-centri-di-formazione","tag-centri-emagister","tag-noticiasskuola","tag-edi-ermes","tag-1098"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La dieta chetogenica, i benefici oltre il trend - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La dieta chetogenica, i benefici oltre il trend - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"Sono ormai diversi anni che si sente parlare sempre pi\u00f9 spesso della\u00a0dieta chetogenica, un programma nutrizionale che purtroppo troppo spesso viene operato in maniera ingiustificatamente estrema. Si tratta di diete ferree a base di sole proteine, con calorie molto basse e soprattutto proposta da chi non solo non dovrebbe o potrebbe farlo, ma che non [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-10T09:12:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-01T10:00:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/03\/mark-deyoung-mjcJ0FFgdWI-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1917\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Italia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Italia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-dieta-chetogenica-i-benefici-oltre-il-trend\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-dieta-chetogenica-i-benefici-oltre-il-trend\\\/\"},\"author\":{\"name\":\"Redazione Italia\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/6a9d1521294589a00d6bc89c01249ec9\"},\"headline\":\"La dieta chetogenica, i benefici oltre il trend\",\"datePublished\":\"2021-03-10T09:12:42+00:00\",\"dateModified\":\"2021-04-01T10:00:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-dieta-chetogenica-i-benefici-oltre-il-trend\\\/\"},\"wordCount\":463,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-dieta-chetogenica-i-benefici-oltre-il-trend\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/mark-deyoung-mjcJ0FFgdWI-unsplash.jpg\",\"keywords\":[\"Centri di Formazione\",\"centri emagister\",\"noticiasSkuola\",\"edi.ermes\",\"30547050082951515368556665514557\"],\"articleSection\":[\"I Nostri Clienti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-dieta-chetogenica-i-benefici-oltre-il-trend\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-dieta-chetogenica-i-benefici-oltre-il-trend\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-dieta-chetogenica-i-benefici-oltre-il-trend\\\/\",\"name\":\"La dieta chetogenica, i benefici oltre il trend - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-dieta-chetogenica-i-benefici-oltre-il-trend\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-dieta-chetogenica-i-benefici-oltre-il-trend\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/mark-deyoung-mjcJ0FFgdWI-unsplash.jpg\",\"datePublished\":\"2021-03-10T09:12:42+00:00\",\"dateModified\":\"2021-04-01T10:00:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-dieta-chetogenica-i-benefici-oltre-il-trend\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-dieta-chetogenica-i-benefici-oltre-il-trend\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-dieta-chetogenica-i-benefici-oltre-il-trend\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/mark-deyoung-mjcJ0FFgdWI-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/mark-deyoung-mjcJ0FFgdWI-unsplash.jpg\",\"width\":1917,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-dieta-chetogenica-i-benefici-oltre-il-trend\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Nostri Clienti\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/i-nostri-clienti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La dieta chetogenica, i benefici oltre il trend\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/6a9d1521294589a00d6bc89c01249ec9\",\"name\":\"Redazione Italia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"caption\":\"Redazione Italia\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/redazione-italia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La dieta chetogenica, i benefici oltre il trend - Emagister Blog Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/","og_locale":"it_IT","og_type":"article","og_title":"La dieta chetogenica, i benefici oltre il trend - Emagister Blog Italia","og_description":"Sono ormai diversi anni che si sente parlare sempre pi\u00f9 spesso della\u00a0dieta chetogenica, un programma nutrizionale che purtroppo troppo spesso viene operato in maniera ingiustificatamente estrema. Si tratta di diete ferree a base di sole proteine, con calorie molto basse e soprattutto proposta da chi non solo non dovrebbe o potrebbe farlo, ma che non [&hellip;]","og_url":"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2021-03-10T09:12:42+00:00","article_modified_time":"2021-04-01T10:00:36+00:00","og_image":[{"width":1917,"height":1280,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/03\/mark-deyoung-mjcJ0FFgdWI-unsplash.jpg","type":"image\/jpeg"}],"author":"Redazione Italia","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Redazione Italia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/"},"author":{"name":"Redazione Italia","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/6a9d1521294589a00d6bc89c01249ec9"},"headline":"La dieta chetogenica, i benefici oltre il trend","datePublished":"2021-03-10T09:12:42+00:00","dateModified":"2021-04-01T10:00:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/"},"wordCount":463,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/03\/mark-deyoung-mjcJ0FFgdWI-unsplash.jpg","keywords":["Centri di Formazione","centri emagister","noticiasSkuola","edi.ermes","30547050082951515368556665514557"],"articleSection":["I Nostri Clienti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/","url":"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/","name":"La dieta chetogenica, i benefici oltre il trend - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/03\/mark-deyoung-mjcJ0FFgdWI-unsplash.jpg","datePublished":"2021-03-10T09:12:42+00:00","dateModified":"2021-04-01T10:00:36+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/03\/mark-deyoung-mjcJ0FFgdWI-unsplash.jpg","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/03\/mark-deyoung-mjcJ0FFgdWI-unsplash.jpg","width":1917,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/la-dieta-chetogenica-i-benefici-oltre-il-trend\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"I Nostri Clienti","item":"https:\/\/www.emagister.it\/blog\/category\/i-nostri-clienti\/"},{"@type":"ListItem","position":3,"name":"La dieta chetogenica, i benefici oltre il trend"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/6a9d1521294589a00d6bc89c01249ec9","name":"Redazione Italia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","caption":"Redazione Italia"},"url":"https:\/\/www.emagister.it\/blog\/author\/redazione-italia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/7688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/161"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=7688"}],"version-history":[{"count":4,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/7688\/revisions"}],"predecessor-version":[{"id":7734,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/7688\/revisions\/7734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/7689"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=7688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=7688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=7688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}