{"id":7830,"date":"2021-05-06T07:01:47","date_gmt":"2021-05-06T07:01:47","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=7830"},"modified":"2021-05-06T10:16:55","modified_gmt":"2021-05-06T10:16:55","slug":"scopri-il-programma-europeo-garanzia-giovani","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/","title":{"rendered":"Scopri il Programma Europeo Garanzia Giovani"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Tra le priorit\u00e0 dell\u2019<\/span><span style=\"font-weight: 400;\">Unione Europea<\/span><span style=\"font-weight: 400;\">, c\u2019\u00e8 quella sulla lotta contro la disoccupazione giovanile che purtroppo \u00e8 presente in diversi Stati Membri, con un tasso che supera il 25%.<\/span><\/p>\n<p><!--more--><\/p>\n<p><span style=\"font-weight: 400;\">Per questo motivo, tra i tanti <\/span><span style=\"font-weight: 400;\">progetti europei<\/span><span style=\"font-weight: 400;\"> previsti nell\u2019UE, dal 2013 \u00e8 stato istituito un programma che possa garantire ai giovani formazione, sostegno e sistemi di inserimento nel mondo del lavoro.<\/span><\/p>\n<h2><b>Garanzia Giovani: cos\u2019\u00e8?<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Garanzia Giovani \u00e8 il programma europeo nato per supportare e migliorare l\u2019occupabilit\u00e0 giovanile nei diversi Stati Membri attraverso servizi dedicati ai giovani di et\u00e0 compresa tra i 15 e i 29 anni.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Per partecipare al programma \u00e8 necessario:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">avere un\u2019et\u00e0 tra i 15 e i 29 anni;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">non essere impegnato in percorsi scolastici-accademici ed attivit\u00e0 lavorative (NEET- Not in Education, Employment or Training);<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">essere residenti o soggiornare regolarmente in un paese europeo.<\/span><\/li>\n<\/ul>\n<h3><b>Contenuti e servizi del programma<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Garanzia Giovani prevede diversi servizi quali:<\/span><\/p>\n<p><b>Accoglienza<\/b><span style=\"font-weight: 400;\">: ogni regione possiede degli sportelli specializzati che offrono informazioni sul funzionamento del programma e sui servizi disponibili in ambito regionale.<\/span><\/p>\n<p><b>Orientamento<\/b><span style=\"font-weight: 400;\">: l\u2019utente avr\u00e0 modo di svolgere un colloquio individuale presso il servizio specializzato assegnato dalla Regione, in cui potr\u00e0 esprimere le proprie esigenze e necessit\u00e0.<\/span><\/p>\n<p><b>Formazione: <\/b><span style=\"font-weight: 400;\">grazie a questo programma \u00e8 possibile cominciare un percorso di formazione sia per<strong><a href=\"https:\/\/www.emagister.it\/corsi_joint_accademy-cen-106716.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-7655 size-full\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/03\/Joint-Accademy.png\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/strong> l\u2019inserimento nel mondo del lavoro sia per riprendere percorsi formativi. (Quest\u2019ultimo destinato ai giovani di et\u00e0 inferiore ai 19 anni).<\/span><\/p>\n<p><b>Accompagnamento al lavoro<\/b><span style=\"font-weight: 400;\">: processo in cui l\u2019utente segue un percorso personalizzato con strumenti e misure specifiche definite durante il colloquio di orientamento.<\/span><\/p>\n<p><b>Apprendistato<\/b><span style=\"font-weight: 400;\">: contratto di lavoro a tempo indeterminato che prevede un percorso formativo obbligatorio dove l\u2019azienda fornisce nozioni e competenze pratiche al giovane in modo che possa \u201capprendere\u201d il mestiere ed inserirsi nel mondo lavorativo.<\/span><\/p>\n<p><b>Tirocini<\/b><span style=\"font-weight: 400;\">: grazie all\u2019esperienza di tirocinio i giovani possono vivere un\u2019esperienza formativa pratica in un\u2019azienda.<\/span><\/p>\n<p><b>Servizio Civile<\/b><span style=\"font-weight: 400;\">: il programma di Servizio Civile prevede progetti di un anno di attivit\u00e0 e formazione costruiti intorno al concetto di volontariato, per promuovere pace, cittadinanza attiva e partecipazione dei giovani.<\/span><\/p>\n<p><b>Sostegno all\u2019autoimprenditorialit\u00e0<\/b><span style=\"font-weight: 400;\">: Garanzia Giovani propone dei servizi che possano supportare e perfezionare le abilit\u00e0 imprenditoriali di giovani di et\u00e0 compresa tra i 18 e i 29 anni per poter avviare successivamente un\u2019attivit\u00e0 propria.<\/span><\/p>\n<p><b>Mobilit\u00e0 professionale in Italia o in un Paese UE<\/b><span style=\"font-weight: 400;\">: possibilit\u00e0 di svolgere esperienze professionali in Italia o all\u2019estero con un supporto economico di 6 mesi fornito dal programma.<\/span><\/p>\n<p><b>Bonus occupazionale per le imprese<\/b><span style=\"font-weight: 400;\">: <\/span><span style=\"font-weight: 400;\">Garanzia Giovani prevede delle agevolazioni fiscali per le imprese che assumono i giovani, incoraggiando cos\u00ec il loro inserimento nel mondo del lavoro.<\/span><\/p>\n<p><b>Formazione a distanza<\/b><span style=\"font-weight: 400;\">: possibilit\u00e0 di intraprendere percorsi di formazione online.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sei interessato a ricevere maggiori informazioni sui progetti\u00a0 promossi dalla <a href=\"https:\/\/www.emagister.it\/corsi_joint_accademy-ef106716.htm\" target=\"_blank\" rel=\"noopener\"><strong>Joint Accademy<\/strong><\/a>? Mettiti in\u00a0<a href=\"https:\/\/www.emagister.it\/contact\/student\" target=\"_blank\" rel=\"noopener\">contatto<\/a>\u00a0con lo staff Emagister, sarai ricontattato da un nostro operatore che ti illustrer\u00e0 tutta l\u2019offerta formativa disponibile!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra le priorit\u00e0 dell\u2019Unione Europea, c\u2019\u00e8 quella sulla lotta contro la disoccupazione giovanile che purtroppo \u00e8 presente in diversi Stati Membri, con un tasso che supera il 25%.<\/p>\n","protected":false},"author":164,"featured_media":7841,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[260,592,867,1106,1107],"class_list":["post-7830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-clienti","tag-centri-di-formazione","tag-centri-emagister","tag-noticiasskuola","tag-1106","tag-joint-accademy"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scopri il Programma Europeo Garanzia Giovani - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scopri il Programma Europeo Garanzia Giovani - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"Tra le priorit\u00e0 dell\u2019Unione Europea, c\u2019\u00e8 quella sulla lotta contro la disoccupazione giovanile che purtroppo \u00e8 presente in diversi Stati Membri, con un tasso che supera il 25%.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-06T07:01:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-06T10:16:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/04\/Garanzia-Giovani.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1189\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/scopri-il-programma-europeo-garanzia-giovani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/scopri-il-programma-europeo-garanzia-giovani\\\/\"},\"author\":{\"name\":\"Redazione Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\"},\"headline\":\"Scopri il Programma Europeo Garanzia Giovani\",\"datePublished\":\"2021-05-06T07:01:47+00:00\",\"dateModified\":\"2021-05-06T10:16:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/scopri-il-programma-europeo-garanzia-giovani\\\/\"},\"wordCount\":464,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/scopri-il-programma-europeo-garanzia-giovani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Garanzia-Giovani.jpg\",\"keywords\":[\"Centri di Formazione\",\"centri emagister\",\"noticiasSkuola\",\"99992269674249392522766775093140\",\"Joint Accademy\"],\"articleSection\":[\"I Nostri Clienti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/scopri-il-programma-europeo-garanzia-giovani\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/scopri-il-programma-europeo-garanzia-giovani\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/scopri-il-programma-europeo-garanzia-giovani\\\/\",\"name\":\"Scopri il Programma Europeo Garanzia Giovani - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/scopri-il-programma-europeo-garanzia-giovani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/scopri-il-programma-europeo-garanzia-giovani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Garanzia-Giovani.jpg\",\"datePublished\":\"2021-05-06T07:01:47+00:00\",\"dateModified\":\"2021-05-06T10:16:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/scopri-il-programma-europeo-garanzia-giovani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/scopri-il-programma-europeo-garanzia-giovani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/scopri-il-programma-europeo-garanzia-giovani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Garanzia-Giovani.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Garanzia-Giovani.jpg\",\"width\":1920,\"height\":1189},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/scopri-il-programma-europeo-garanzia-giovani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Nostri Clienti\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/i-nostri-clienti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Scopri il Programma Europeo Garanzia Giovani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\",\"name\":\"Redazione Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Redazione Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/redazione-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scopri il Programma Europeo Garanzia Giovani - Emagister Blog Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/","og_locale":"it_IT","og_type":"article","og_title":"Scopri il Programma Europeo Garanzia Giovani - Emagister Blog Italia","og_description":"Tra le priorit\u00e0 dell\u2019Unione Europea, c\u2019\u00e8 quella sulla lotta contro la disoccupazione giovanile che purtroppo \u00e8 presente in diversi Stati Membri, con un tasso che supera il 25%.","og_url":"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2021-05-06T07:01:47+00:00","article_modified_time":"2021-05-06T10:16:55+00:00","og_image":[{"width":1920,"height":1189,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/04\/Garanzia-Giovani.jpg","type":"image\/jpeg"}],"author":"Redazione Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Redazione Emagister","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/"},"author":{"name":"Redazione Emagister","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897"},"headline":"Scopri il Programma Europeo Garanzia Giovani","datePublished":"2021-05-06T07:01:47+00:00","dateModified":"2021-05-06T10:16:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/"},"wordCount":464,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/04\/Garanzia-Giovani.jpg","keywords":["Centri di Formazione","centri emagister","noticiasSkuola","99992269674249392522766775093140","Joint Accademy"],"articleSection":["I Nostri Clienti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/","url":"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/","name":"Scopri il Programma Europeo Garanzia Giovani - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/04\/Garanzia-Giovani.jpg","datePublished":"2021-05-06T07:01:47+00:00","dateModified":"2021-05-06T10:16:55+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/04\/Garanzia-Giovani.jpg","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/04\/Garanzia-Giovani.jpg","width":1920,"height":1189},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/scopri-il-programma-europeo-garanzia-giovani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"I Nostri Clienti","item":"https:\/\/www.emagister.it\/blog\/category\/i-nostri-clienti\/"},{"@type":"ListItem","position":3,"name":"Scopri il Programma Europeo Garanzia Giovani"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897","name":"Redazione Emagister","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Redazione Emagister"},"url":"https:\/\/www.emagister.it\/blog\/author\/redazione-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/7830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=7830"}],"version-history":[{"count":2,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/7830\/revisions"}],"predecessor-version":[{"id":8016,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/7830\/revisions\/8016"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/7841"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=7830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=7830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=7830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}