{"id":8139,"date":"2021-05-26T08:49:51","date_gmt":"2021-05-26T08:49:51","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=8139"},"modified":"2021-06-02T15:23:48","modified_gmt":"2021-06-02T15:23:48","slug":"il-caos-comunicativo-su-astrazeneca","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/","title":{"rendered":"Il Caos comunicativo su AstraZeneca"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">La <\/span><b>comunicazione<\/b><span style=\"font-weight: 400;\">\u00a0 \u00e8 uno degli aspetti basilari dell\u2019esistenza umana, il termine deriva dal latino <\/span><i><span style=\"font-weight: 400;\">communicare: <\/span><\/i><span style=\"font-weight: 400;\">mettere in comune ed \u00e8 la base che ha permesso lo sviluppo di ogni tipo di fenomeno sociale, ideologico, politico e religioso.<\/span><!--more--><\/p>\n<p><span style=\"font-weight: 400;\">Osservando il fenomeno della comunicazione \u00e8 necessario sottolineare come esso sia un elemento imprescindibile della realt\u00e0 umana. Paul Watzlawick nei suoi Assiomi della Comunicazione affermava che \u201c<\/span><i><span style=\"font-weight: 400;\">non si pu\u00f2 non comunicare<\/span><\/i><span style=\"font-weight: 400;\">\u201d e che l\u2019assenza di una comunicazione esplicita comunica essa stessa qualcosa e veicola un contenuto implicito di informazioni.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se vista da questa prospettiva, la capacit\u00e0 umana di veicolare informazioni diventa un fenomeno alquanto affascinante, che richiede una particolare attenzione tramite l\u2019utilizzo di contenuti chiari, semplici, diretti, ma soprattutto corrispondenti alla realt\u00e0 e perci\u00f2 non falsi e di dubbia provenienza.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se si osserva lo scenario sociale odierno legato alla pandemia di <\/span><b>COVID19<\/b><span style=\"font-weight: 400;\"> appare pi\u00f9 che mai importante una comunicazione coerente e valida. L\u2019esigenza di trasmettere informazioni chiare e inequivocabili diviene ancora pi\u00f9 urgente nel caso di stati di emergenza come quello che stiamo vivendo negli ultimi mesi.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un chiaro esempio di comunicazione inesatta con conseguenti effetti dannosi \u00e8 il tanto discusso \u201c<\/span><b>Caso AstraZeneca<\/b><span style=\"font-weight: 400;\">\u201d, nota casa farmaceutica produttrice di una tipologia di vaccino che protegge dal contagio di COVID19 e al quale ha dato anche il nome.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L\u2019evento di cronaca che coinvolge tutti i paesi Europei riguarda i possibili effetti collaterali dovuti alla somministrazione di tale vaccino, che hanno condotto alcuni Stati a scegliere di sospenderne l\u2019utilizzo. Scelta non condivisa da tutte le nazioni che hanno invece continuato le campagne di vaccinazione con il siero Astrazeneca.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il nostro paese, dopo aver rispettato lo stop richiesto dall\u2019<\/span><b>OMS<\/b><span style=\"font-weight: 400;\"> (<\/span><b>Organizzazione Mondiale della Sanit\u00e0<\/b><span style=\"font-weight: 400;\">) per degli accertamenti, ha proseguito nell\u2019importazione e somministrazione dei vaccini Astrazeneca. Questa scelta ha certamente acceso un forte dibattito nell\u2019opinione pubblica, a volte con toni sensazionalistici, riguardo la correttezza della decisione di procedere nell\u2019utilizzo del vaccino in questione; molti dei cittadini italiani chiamati ad essere vaccinati con AstraZeneca hanno infatti rinunciato al proprio turno di vaccinazione.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A questo punto \u00e8 doveroso specificare che i dubbi e le paure riguardo la presunta pericolosit\u00e0 del vaccino, non sono mai stati supportati da evidenze di carattere scientifico. Al contrario, la comunit\u00e0 scientifica ha dichiarato che non esiste diretta correlazione tra sintomi e vaccino; la fonte principale di tali problemi \u00e8 una <\/span><b>comunicazione errata<\/b><span style=\"font-weight: 400;\"> con assenza di chiare linee guida che fornisca a tutti informazioni complete ed esaustiva e che non lasci spazio ad interpretazioni.\u00a0<a href=\"https:\/\/www.emagister.it\/corsi_make_it-ef74422.htm\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-4585 size-full\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/11\/Make-It-So.png\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il tipo comunicazione creatasi attorno al caso Astrazeneca ha avuto un diretto effetto anche sul <\/span><b>marketing farmaceutico<\/b><span style=\"font-weight: 400;\">, \u00e8 stato infatti riscontrato un incremento nelle\u00a0 vendite di prodotti privi di alcun beneficio medico ma semplici integratori che hanno avviato una strategia di marketing e una campagna pubblicitaria fuorviante e non attendibile scientificamente affermando l\u2019esistenza di diretti effetti nella protezione dal contagio di <\/span><b>COVID19<\/b><span style=\"font-weight: 400;\"> se assunti regolarmente; alcuni di questi prodotti hanno incrementato le proprie vendite fin anche del 68%.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Di fronte a fenomeni di questo tipo appare chiaro quanto sia fondamentale educare ad una comunicazione chiara ed efficace che anche se veicola informazioni scientifiche e specialistiche riesca ed essere resa chiara e comprensibile anche ai \u201cnon addetti ai lavori\u201d e perci\u00f2 sia in grado di consegnare il messaggio a chiunque abbia diritto a conoscere le informazioni indispensabili alla tutela della propria salute.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se sei interessato ad approfondire le tematiche di <\/span><b>Comunicazione Scientifica <\/b><span style=\"font-weight: 400;\">per acquisire i giusti strumenti per un\u2019efficace divulgazione scientifica, ti consigliamo il <\/span><b>Master in Comunicazione Scientifica<\/b><span style=\"font-weight: 400;\"> erogato da Make it So che partir\u00e0 nella sua IX Edizione il <\/span><b>18 Settembre<\/b><span style=\"font-weight: 400;\"> in modalit\u00e0 Online, e dunque fruibile da chiunque indipendentemente dall\u2019ubicazione geografica.<\/span><\/p>\n<p>Vuoi conoscere le opzioni di formazione disponibili offerte da Make it so? Mettiti in contatto con Emagister per ricevere maggiori informazioni. Se hai gi\u00e0 frequentato questo corso non dimenticarti di farci sapere la tua opinione compilando questo\u00a0<a href=\"https:\/\/www.emagister.it\/reviews\/add\" target=\"_blank\" rel=\"noopener\">form<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La comunicazione\u00a0 \u00e8 uno degli aspetti basilari dell\u2019esistenza umana, il termine deriva dal latino communicare: mettere in comune ed \u00e8 la base che ha permesso lo sviluppo di ogni tipo di fenomeno sociale, ideologico, politico e religioso.<\/p>\n","protected":false},"author":161,"featured_media":7710,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[260,592,867,954,955],"class_list":["post-8139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-clienti","tag-centri-di-formazione","tag-centri-emagister","tag-noticiasskuola","tag-954","tag-make-it-so"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Caos comunicativo su AstraZeneca - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Caos comunicativo su AstraZeneca - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"La comunicazione\u00a0 \u00e8 uno degli aspetti basilari dell\u2019esistenza umana, il termine deriva dal latino communicare: mettere in comune ed \u00e8 la base che ha permesso lo sviluppo di ogni tipo di fenomeno sociale, ideologico, politico e religioso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-26T08:49:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-02T15:23:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/03\/bermix-studio-m0hz75hjXEo-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Italia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Italia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-caos-comunicativo-su-astrazeneca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-caos-comunicativo-su-astrazeneca\\\/\"},\"author\":{\"name\":\"Redazione Italia\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/6a9d1521294589a00d6bc89c01249ec9\"},\"headline\":\"Il Caos comunicativo su AstraZeneca\",\"datePublished\":\"2021-05-26T08:49:51+00:00\",\"dateModified\":\"2021-06-02T15:23:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-caos-comunicativo-su-astrazeneca\\\/\"},\"wordCount\":646,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-caos-comunicativo-su-astrazeneca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/bermix-studio-m0hz75hjXEo-unsplash.jpg\",\"keywords\":[\"Centri di Formazione\",\"centri emagister\",\"noticiasSkuola\",\"60753100102569516950705268674568\",\"Make It So\"],\"articleSection\":[\"I Nostri Clienti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-caos-comunicativo-su-astrazeneca\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-caos-comunicativo-su-astrazeneca\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-caos-comunicativo-su-astrazeneca\\\/\",\"name\":\"Il Caos comunicativo su AstraZeneca - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-caos-comunicativo-su-astrazeneca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-caos-comunicativo-su-astrazeneca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/bermix-studio-m0hz75hjXEo-unsplash.jpg\",\"datePublished\":\"2021-05-26T08:49:51+00:00\",\"dateModified\":\"2021-06-02T15:23:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-caos-comunicativo-su-astrazeneca\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-caos-comunicativo-su-astrazeneca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-caos-comunicativo-su-astrazeneca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/bermix-studio-m0hz75hjXEo-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/bermix-studio-m0hz75hjXEo-unsplash.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/il-caos-comunicativo-su-astrazeneca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Nostri Clienti\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/i-nostri-clienti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il Caos comunicativo su AstraZeneca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/6a9d1521294589a00d6bc89c01249ec9\",\"name\":\"Redazione Italia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"caption\":\"Redazione Italia\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/redazione-italia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Caos comunicativo su AstraZeneca - Emagister Blog Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/","og_locale":"it_IT","og_type":"article","og_title":"Il Caos comunicativo su AstraZeneca - Emagister Blog Italia","og_description":"La comunicazione\u00a0 \u00e8 uno degli aspetti basilari dell\u2019esistenza umana, il termine deriva dal latino communicare: mettere in comune ed \u00e8 la base che ha permesso lo sviluppo di ogni tipo di fenomeno sociale, ideologico, politico e religioso.","og_url":"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2021-05-26T08:49:51+00:00","article_modified_time":"2021-06-02T15:23:48+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/03\/bermix-studio-m0hz75hjXEo-unsplash.jpg","type":"image\/jpeg"}],"author":"Redazione Italia","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Redazione Italia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/"},"author":{"name":"Redazione Italia","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/6a9d1521294589a00d6bc89c01249ec9"},"headline":"Il Caos comunicativo su AstraZeneca","datePublished":"2021-05-26T08:49:51+00:00","dateModified":"2021-06-02T15:23:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/"},"wordCount":646,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/03\/bermix-studio-m0hz75hjXEo-unsplash.jpg","keywords":["Centri di Formazione","centri emagister","noticiasSkuola","60753100102569516950705268674568","Make It So"],"articleSection":["I Nostri Clienti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/","url":"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/","name":"Il Caos comunicativo su AstraZeneca - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/03\/bermix-studio-m0hz75hjXEo-unsplash.jpg","datePublished":"2021-05-26T08:49:51+00:00","dateModified":"2021-06-02T15:23:48+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/03\/bermix-studio-m0hz75hjXEo-unsplash.jpg","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/03\/bermix-studio-m0hz75hjXEo-unsplash.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/il-caos-comunicativo-su-astrazeneca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"I Nostri Clienti","item":"https:\/\/www.emagister.it\/blog\/category\/i-nostri-clienti\/"},{"@type":"ListItem","position":3,"name":"Il Caos comunicativo su AstraZeneca"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/6a9d1521294589a00d6bc89c01249ec9","name":"Redazione Italia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","caption":"Redazione Italia"},"url":"https:\/\/www.emagister.it\/blog\/author\/redazione-italia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/8139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/161"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=8139"}],"version-history":[{"count":3,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/8139\/revisions"}],"predecessor-version":[{"id":8155,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/8139\/revisions\/8155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/7710"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=8139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=8139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=8139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}