{"id":8184,"date":"2021-06-08T08:18:49","date_gmt":"2021-06-08T08:18:49","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=8184"},"modified":"2021-06-11T12:54:45","modified_gmt":"2021-06-11T12:54:45","slug":"attivita-per-allenare-la-mente-nellanziano","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/","title":{"rendered":"Attivit\u00e0 per allenare la mente nell&#8217;anziano"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Mantenere la mente attiva ed allenata \u00e8 una priorit\u00e0 per chi giunge alle soglie della terza et\u00e0, spesso un piccolo allenamento quotidiano pu\u00f2 migliorare nettamente <strong>la qualit\u00e0 della vita<\/strong>. Infatti, continuare ad allenare le proprie capacit\u00e0 logico deduttive pu\u00f2 contribuire a<\/span><span style=\"font-weight: 400;\">\u00a0ritardare la nascita di eventuali <strong>malattie e patologie neurodegenerative,<\/strong> aiutando a mantenersi attivi pi\u00f9 a lungo. Naturalmente tutto questo dovr\u00e0 essere accompagnato da uno stile di vita sano e da una dieta varia ed equilibrata, praticare sport e ridurre al minimo le cattive abitudini. Tutti questi fattori messi insieme permettono di avere un\u2019aspettativa di vita pi\u00f9 lunga, ponendo particolare attenzione alla mente.<\/span><!--more--><\/p>\n<p><span style=\"font-weight: 400;\">Il cervello funziona un po&#8217; come un muscolo e un allenamento costante pu\u00f2 migliorarne le prestazione e far durare pi\u00f9 a lungo la sua salute. Le possibilit\u00e0 sono davvero tantissime, <strong>semplici attivit\u00e0 quotidiane<\/strong> e piccoli passatempi possono rivelarsi davvero utili.<\/span><\/p>\n<h2><b>Quali sono le attivit\u00e0 per anziani pi\u00f9 indicate<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Non sar\u00e0 difficile trovare l&#8217;attivit\u00e0 logica pi\u00f9 adatta a stimolare i nostri neuroni: le\u00a0<\/span><b>attivit\u00e0 per anziani<\/b><span style=\"font-weight: 400;\">\u00a0sono veramente tante e non devono necessariamente richiedere complessi calcoli matematici, si pu\u00f2 optare per una dimensione pi\u00f9 ludica e piacevole.<\/span><span style=\"font-weight: 400;\">\u00a0Tra i passatempi pi\u00f9 amati, ma anche pi\u00f9 efficaci c&#8217;\u00e8 senza dubbio la lettura: le pagine di un buon libro stimolano la fantasia, allenano la creativit\u00e0 e permettono di conoscere cose nuove.\u00a0 Attraverso la lettura \u00e8 possibile<strong> migliorare le proprie attivit\u00e0 celebrali<\/strong> e rallentare la degenerazione del cervello, nonch\u00e9 aumentare la socializzazione attraverso il confronto con gli altri. Un\u2019altra attivit\u00e0 che \u00e8 possibile svolgere per allenare la mente degli anziani \u00e8 lo sport.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Abbiamo spesso parlato su questo blog dei numerosi benefici dell&#8217;attivit\u00e0 fisica, ma forse non tutti sanno che praticare uno sport permette di avere non solo un corpo sano ma anche una mente pi\u00f9 giovane. L\u2019attivit\u00e0 sportiva infatti \u00e8 in grado di stimolare l\u2019ippocampo e di favorire la memorizzazione. Certamente bisogner\u00e0 trovare l&#8217;attivit\u00e0 pi\u00f9 consona ai nostri ritmi e alla nostra forma fisica, prediligendo le attivit\u00e0 di ginnastica dolce come lo <\/span><b>yoga <\/b><span style=\"font-weight: 400;\">oppure il pilates. Un altro modo per mantenersi attivi e allo stesso tempo<\/span><b>\u00a0allenare la mente \u00e8 coltivare una passione o un hobby<\/b><span style=\"font-weight: 400;\">. Che sia la cucina, il giardinaggio, il fai da te o il cucito non importa: tutte queste attivit\u00e0 mentali che richiedono uno sforzo di concentrazione e un certo impegno sono perfette per rallentare il processo di<a href=\"https:\/\/www.emagister.it\/corsi_corsicef_centro_europeo_di_formazione-cen-58031.htm\" target=\"_blank\" rel=\"nofollow noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-4290 size-full\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2019\/10\/CEF.jpg\" alt=\"\" width=\"220\" height=\"147\" \/><\/a> invecchiamento mentale tipico delle persone anziane.<\/span><\/p>\n<h2><b>Allenare la mente degli anziani con un assistente alla persona<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Non \u00e8 sempre facile per una persona anziana trovare gli stimoli giusti per mantenere uno stile di vita attivo, per questo motivo l&#8217;\u00a0<\/span><b>assist<\/b><b>ente alla persona pu\u00f2 essere un valido aiuto<\/b><span style=\"font-weight: 400;\">, si tratta di una figura professionale che ha acquisito tutte le competenze necessarie per <\/span><b>assistere un anziano<\/b><span style=\"font-weight: 400;\"> e accompagnarlo nel suo percorso di vita. Per <\/span><b>svolgere questa professione<\/b><span style=\"font-weight: 400;\">\u00a0e prendersi cura degli anziani \u00e8 necessario ottenere un attestato seguendo degli specifici corsi di formazione. Ad esempio i <\/span><b>corsi CEF<\/b><span style=\"font-weight: 400;\"> sono dei percorsi studiati appositamente per acquisire una preparazione adeguata in questo settore al fine di entrare nel mondo del lavoro. Sono corsi svolti esclusivamente <\/span><b>online<\/b><span style=\"font-weight: 400;\"> e che permettono una certa flessibilit\u00e0 venendo incontro alle esigenze di tutti, anche di chi lavora. I <\/span><b>corsi CEF <\/b><span style=\"font-weight: 400;\">sono tenuti da professionisti ed esperti di alto livello in diverse aree formative. Inoltre ogni studente ha la possibilit\u00e0 di adattare il piano di studi e la mole di lavoro in base alle proprie necessit\u00e0.\u00a0<\/span><\/p>\n<h2><b>Consigli importanti per allenare la mente degli anziani<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Gli spunti che abbiamo fornito in questo articolo sono delle ottime\u00a0<\/span><b>attivit\u00e0 mentali<\/b><span style=\"font-weight: 400;\"> e fisiche, in alternativa, per memoria e rendere pi\u00f9 giovane la mente di un anziano \u00e8 possibile anche svolgere alcune attivit\u00e0 ludiche piuttosto semplici. Una di queste \u00e8 ad esempio il gioco del burraco (o altri giochi di carte in generale): infatti il gioco ha delle grandi potenzialit\u00e0 nello stimolare la mente e l\u2019attivit\u00e0 cognitiva. Inoltre, dal momento che si tratta di un gioco che deve essere fatto in gruppo, \u00e8 possibile anche favorire la comunicazione e la socializzazione.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sembrer\u00e0 strano, ma secondo recenti studi, anche<strong> i social network possono essere un ottimo stimolo<\/strong> per la mente delle persone anziane. Nello specifico \u00e8 possibile proporre all&#8217;anziano strumenti tecnologici come smartphone, computer o tablet per acquisire nuove abilit\u00e0 e mantenere la mente sveglia. Allo stesso modo anche l\u2019uso dei social network e di internet in generale consente di esplorare realt\u00e0 completamente nuove che stimolano diverse aree cerebrali. Da non dimenticare poi l\u2019ascolto della musica e i giochi come rebus, parole crociate o altri rompicapi, perfetti per <\/span><b>allenare la mente<\/b><span style=\"font-weight: 400;\"> e favorire lo sviluppo della memoria a lungo termine.<\/span><\/p>\n<p>Hai gi\u00e0 frequentato un corso online con CEF? Facci sapere la tua\u00a0<a href=\"https:\/\/www.emagister.it\/reviews\/add\" target=\"_blank\" rel=\"noopener\">opinione<\/a>\u00a0e potrai partecipare all\u2019estrazione di un buono formazione del valore di 3.000 \u20ac.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mantenere la mente attiva ed allenata \u00e8 una priorit\u00e0 per chi giunge alle soglie della terza et\u00e0, spesso un piccolo allenamento quotidiano pu\u00f2 migliorare nettamente la qualit\u00e0 della vita. Infatti, continuare ad allenare le proprie capacit\u00e0 logico deduttive pu\u00f2 contribuire a\u00a0ritardare la nascita di eventuali malattie e patologie neurodegenerative, aiutando a mantenersi attivi pi\u00f9 a [&hellip;]<\/p>\n","protected":false},"author":161,"featured_media":8185,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[260,592,867,923,924],"class_list":["post-8184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-clienti","tag-centri-di-formazione","tag-centri-emagister","tag-noticiasskuola","tag-923","tag-centro-europeo-di-formazione-cef"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Attivit\u00e0 per allenare la mente nell&#039;anziano - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Attivit\u00e0 per allenare la mente nell&#039;anziano - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"Mantenere la mente attiva ed allenata \u00e8 una priorit\u00e0 per chi giunge alle soglie della terza et\u00e0, spesso un piccolo allenamento quotidiano pu\u00f2 migliorare nettamente la qualit\u00e0 della vita. Infatti, continuare ad allenare le proprie capacit\u00e0 logico deduttive pu\u00f2 contribuire a\u00a0ritardare la nascita di eventuali malattie e patologie neurodegenerative, aiutando a mantenersi attivi pi\u00f9 a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-08T08:18:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-11T12:54:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/06\/aaron-andrew-ang-jXMGrVYHpK0-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Italia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Italia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/attivita-per-allenare-la-mente-nellanziano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/attivita-per-allenare-la-mente-nellanziano\\\/\"},\"author\":{\"name\":\"Redazione Italia\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/6a9d1521294589a00d6bc89c01249ec9\"},\"headline\":\"Attivit\u00e0 per allenare la mente nell&#8217;anziano\",\"datePublished\":\"2021-06-08T08:18:49+00:00\",\"dateModified\":\"2021-06-11T12:54:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/attivita-per-allenare-la-mente-nellanziano\\\/\"},\"wordCount\":798,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/attivita-per-allenare-la-mente-nellanziano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/aaron-andrew-ang-jXMGrVYHpK0-unsplash.jpg\",\"keywords\":[\"Centri di Formazione\",\"centri emagister\",\"noticiasSkuola\",\"50659050082349536565505351654569\",\"Centro Europeo di Formazione - CEF\"],\"articleSection\":[\"I Nostri Clienti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/attivita-per-allenare-la-mente-nellanziano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/attivita-per-allenare-la-mente-nellanziano\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/attivita-per-allenare-la-mente-nellanziano\\\/\",\"name\":\"Attivit\u00e0 per allenare la mente nell'anziano - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/attivita-per-allenare-la-mente-nellanziano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/attivita-per-allenare-la-mente-nellanziano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/aaron-andrew-ang-jXMGrVYHpK0-unsplash.jpg\",\"datePublished\":\"2021-06-08T08:18:49+00:00\",\"dateModified\":\"2021-06-11T12:54:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/attivita-per-allenare-la-mente-nellanziano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/attivita-per-allenare-la-mente-nellanziano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/attivita-per-allenare-la-mente-nellanziano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/aaron-andrew-ang-jXMGrVYHpK0-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/aaron-andrew-ang-jXMGrVYHpK0-unsplash.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/attivita-per-allenare-la-mente-nellanziano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Nostri Clienti\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/i-nostri-clienti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Attivit\u00e0 per allenare la mente nell&#8217;anziano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/6a9d1521294589a00d6bc89c01249ec9\",\"name\":\"Redazione Italia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g\",\"caption\":\"Redazione Italia\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/redazione-italia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Attivit\u00e0 per allenare la mente nell'anziano - Emagister Blog Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/","og_locale":"it_IT","og_type":"article","og_title":"Attivit\u00e0 per allenare la mente nell'anziano - Emagister Blog Italia","og_description":"Mantenere la mente attiva ed allenata \u00e8 una priorit\u00e0 per chi giunge alle soglie della terza et\u00e0, spesso un piccolo allenamento quotidiano pu\u00f2 migliorare nettamente la qualit\u00e0 della vita. Infatti, continuare ad allenare le proprie capacit\u00e0 logico deduttive pu\u00f2 contribuire a\u00a0ritardare la nascita di eventuali malattie e patologie neurodegenerative, aiutando a mantenersi attivi pi\u00f9 a [&hellip;]","og_url":"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2021-06-08T08:18:49+00:00","article_modified_time":"2021-06-11T12:54:45+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/06\/aaron-andrew-ang-jXMGrVYHpK0-unsplash.jpg","type":"image\/jpeg"}],"author":"Redazione Italia","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Redazione Italia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/"},"author":{"name":"Redazione Italia","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/6a9d1521294589a00d6bc89c01249ec9"},"headline":"Attivit\u00e0 per allenare la mente nell&#8217;anziano","datePublished":"2021-06-08T08:18:49+00:00","dateModified":"2021-06-11T12:54:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/"},"wordCount":798,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/06\/aaron-andrew-ang-jXMGrVYHpK0-unsplash.jpg","keywords":["Centri di Formazione","centri emagister","noticiasSkuola","50659050082349536565505351654569","Centro Europeo di Formazione - CEF"],"articleSection":["I Nostri Clienti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/","url":"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/","name":"Attivit\u00e0 per allenare la mente nell'anziano - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/06\/aaron-andrew-ang-jXMGrVYHpK0-unsplash.jpg","datePublished":"2021-06-08T08:18:49+00:00","dateModified":"2021-06-11T12:54:45+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/06\/aaron-andrew-ang-jXMGrVYHpK0-unsplash.jpg","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/06\/aaron-andrew-ang-jXMGrVYHpK0-unsplash.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/attivita-per-allenare-la-mente-nellanziano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"I Nostri Clienti","item":"https:\/\/www.emagister.it\/blog\/category\/i-nostri-clienti\/"},{"@type":"ListItem","position":3,"name":"Attivit\u00e0 per allenare la mente nell&#8217;anziano"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/6a9d1521294589a00d6bc89c01249ec9","name":"Redazione Italia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c49814e96bee960439972dcf6f75f8bccec87b344d0123c0d1a1675c7a72f6aa?s=96&r=g","caption":"Redazione Italia"},"url":"https:\/\/www.emagister.it\/blog\/author\/redazione-italia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/8184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/161"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=8184"}],"version-history":[{"count":4,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/8184\/revisions"}],"predecessor-version":[{"id":8198,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/8184\/revisions\/8198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/8185"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=8184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=8184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=8184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}