{"id":842,"date":"2015-07-16T09:23:16","date_gmt":"2015-07-16T09:23:16","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=842"},"modified":"2015-07-16T09:23:16","modified_gmt":"2015-07-16T09:23:16","slug":"lavori-assurdi-la-top-10","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/","title":{"rendered":"Lavori assurdi: la Top 10"},"content":{"rendered":"<p>Per trovare un lavoro ci vuole una buona preparazione, <a href=\"https:\/\/www.emagister.it\/\">corsi <\/a>adeguati, magari dei <a href=\"https:\/\/www.emagister.it\/master\/\">master<\/a> o dei <a href=\"https:\/\/www.emagister.it\/corsi_formazione\/\">corsi professionali<\/a>. Poi una ricerca fatta per bene, la <a href=\"https:\/\/www.emagister.it\/blog\/9-consigli-per-migliorare-la-lettera-di-presentazione\/\">lettera di presentazione<\/a> adeguata e il <a href=\"https:\/\/www.emagister.it\/web\/search\/?action=search&amp;origen=buscador_principal&amp;esBusquedaUsuario=1&amp;q=curriculum+vitae\">curriculum<\/a> giusto, una buona preparazione per affrontare il <a href=\"https:\/\/www.emagister.it\/web\/search\/?action=search&amp;origen=buscador_principal&amp;esBusquedaUsuario=1&amp;q=colloquio+di+lavoro\">colloquio di lavoro<\/a>, <a href=\"https:\/\/www.emagister.it\/blog\/stress-da-colloquio-di-lavoro-le-buone-maniere-ti-possono-aiutare\/\">l&#8217;atteggiamento<\/a> giusto e, inultile dirlo, quel pizzico di fortuna che non guasta mai.<\/p>\n<p><!--more-->Ma se pensassimo in grande, rivoluzionando il nostro approccio al lavoro e usassimo tutta questa preparazione psicologica, fisica e culturale per cercare un lavoro alternativo e magari inventarne uno nuovo?<\/p>\n<p>C\u2019\u00e8 chi l\u2019ha fatto. Ecco per voi un elenco dei <b>10 lavori pi\u00f9 strani del mondo<\/b>, tra i pi\u00f9 belli e i pi\u00f9 brutti (per molti dei quali ci vuole un gran coraggio).<\/p>\n<ol>\n<li><b>Temperatore di matite: <\/b>\u00e8 il lavoro di David Rees dal 2010. <b>Tempera a mano<\/b> le matite con dei coltelli speciali per poco pi\u00f9 di 30 euro l\u2019una e te la riconsegna in una tubo di plastica con tappo e certificato di affilatura artigianale. Ha scritto anche un libro:\u00a0<i>How to sharpen pencils.<\/i><\/li>\n<li><b>Tester di giochi d\u2019acqua: <\/b>s\u00ec, avete capito bene. Il lavoro consiste nel girare i parchi d\u2019attrazione del mondo e lanciarsi per gli scivoli d\u2019acqua per testarne la pendenza, la sicurezza, l\u2019impatto dell\u2019acqua ecc. Tommy Lynch lo ha fatto per 4 anni durante i quali ha provato circa 5000 scivoli.<\/li>\n<li><b>Tester di videogiochi: <\/b>se avete la passione per i videogiochi, le dita rapide e stare ore davanti al computer non vi spaventa, siete pronti per cercare questo lavoro. Si tratta di testare i videogiochi prima della loro commercializzazione. Per farlo bisogna spesso passare pi\u00f9 volte per lo stesso quadro cercando eventuali errori di programmazione. Se vi interessa, cercate: usability tester per videogame.<\/li>\n<li><b>Custode dell\u2019isola di Hamilton Island, Australia: <\/b>il primo e pi\u00f9 famoso fu Ben Southall che ebbe il contratto per 6 mesi durante i quali ha vissuto in un&#8217;isola paradisiaca, lontano dallo stress e dalla vita frenetica. Oggi \u00e8 presentatore, videomaker, e ambasciatore del turismo del Queensland.<\/li>\n<li><b>Assaggiatore di gelati:<\/b> la marca Ben&amp;Jerry\u2019s ha assunto un assaggiatore professionista che si occupa di provare diversi sapori alla ricerca di quello giusto da lanciare sul mercato. Per ottenere il massimo, il cucchiaino utilizzato per il test \u00e8 d\u2019oro, materiale totalmente insapore.<\/li>\n<li><b>Assaggiatore di cibo per animali:<\/b> meno fortunati del collega della Ben&amp;Jerry\u2019s, gli assaggiatori di cibo per animali testano il prodotto prima della vendita. Che siano cibi in scatola, crocchette per cani o per gatti, qualcuno li ha assaggiati per assicurasi che il palato dei nostri amati animali non venga deluso.<\/li>\n<li><b>Tester di odori<\/b>: nei casi pi\u00f9 fortunati si tratta di profumi e l\u2019impiegato dovr\u00e0 occuparsi di trovare la migliore fragranza, ma il tester di odori si occupa anche di verificare se un deodorante funziona ed \u00e8 in grado di eliminare l\u2019odore di sudore dalle ascelle delle persone. Per fare questo lavoro ci vuole il naso fino, inutile dirlo (e un gran \u201ccoraggio\u201d).<\/li>\n<li><b>Trasportatore di iceberg: <\/b>la storia ci insegna che un iceberg pu\u00f2 essere molto pericoloso. Ma come si previene il pericolo? L\u2019International Ice Patrol si occupa di spostare gli iceberg che si trovano nelle rotte commerciali delle navi e portarli in acque pi\u00f9 sicure. Lo spostamento pu\u00f2 richiedere anche 150 giorni di navigazione.<\/li>\n<li><b>Professionista di funerali<\/b>: a Taiwan c\u2019\u00e8 un\u2019usanza molto particolare. Durante un funerale si pu\u00f2 richiedere il servizio di un professionista che si occuper\u00e0 di impersonificare il dolore per la perdita del defunto cantando, ballando, piangendo e pregando durante il rito funebre. Il servizio \u00e8 molto costoso quindi solo le famiglie pi\u00f9 ricche possono usufruirne.<\/li>\n<li><b>Esaminatore di dadi<\/b>: si occupa di verificare che i dadi utilizzati nei Casin\u00f3 non abbiamo angoli sproporzionati o altri difetti che potrebbero causare errori nel momento in cui sono tirati dai giocatori. \u00c8 un lavoro che richiede molta pazienza e attenzione per i dettagli.<\/li>\n<\/ol>\n<p>La lista sarebbe ancora lunga: raccoglitori di palline da golf, sessatore di pulcini, pulitore di semafori, lavavetri dei grattacieli e molti altri ancora.<\/p>\n<p>E voi? Qual \u00e8 il lavoro pi\u00f9 strano che avete fatto? E che lavoro sareste disposti a fare tra quelli elencati?<\/p>\n<table border=\"1\" cellspacing=\"2\" cellpadding=\"2\">\n<tbody>\n<tr>\n<td width=\"140\" height=\"192\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<a href=\"https:\/\/www.emagister.it\/blog\/?attachment_id=736\" rel=\"attachment wp-att-736\"><img loading=\"lazy\" decoding=\"async\" alt=\"Elena Gordini\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2014\/12\/Elena-Gordini-150x150.jpg\" width=\"150\" height=\"150\" \/><\/a><\/td>\n<td><strong>Elena Gordini<br \/>\n<\/strong>Traduttrice, blogger e operatrice culturale fra l&#8217;Italia e la Spagna.<strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per trovare un lavoro ci vuole una buona preparazione, corsi adeguati, magari dei master o dei corsi professionali. Poi una ricerca fatta per bene, la lettera di presentazione adeguata e il curriculum giusto, una buona preparazione per affrontare il colloquio di lavoro, l&#8217;atteggiamento giusto e, inultile dirlo, quel pizzico di fortuna che non guasta mai.<\/p>\n","protected":false},"author":3,"featured_media":1077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[76,17,34],"class_list":["post-842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lavoro","tag-lavori-strani","tag-lavoro-2","tag-estero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lavori assurdi: la Top 10 - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lavori assurdi: la Top 10 - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"Per trovare un lavoro ci vuole una buona preparazione, corsi adeguati, magari dei master o dei corsi professionali. Poi una ricerca fatta per bene, la lettera di presentazione adeguata e il curriculum giusto, una buona preparazione per affrontare il colloquio di lavoro, l&#8217;atteggiamento giusto e, inultile dirlo, quel pizzico di fortuna che non guasta mai.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-16T09:23:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2015\/07\/ThinkstockPhotos-481062550.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elena Gordini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elena Gordini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/lavori-assurdi-la-top-10\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/lavori-assurdi-la-top-10\\\/\"},\"author\":{\"name\":\"Elena Gordini\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/3919aff1269d50f0b11c0a55aad646df\"},\"headline\":\"Lavori assurdi: la Top 10\",\"datePublished\":\"2015-07-16T09:23:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/lavori-assurdi-la-top-10\\\/\"},\"wordCount\":700,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/lavori-assurdi-la-top-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/ThinkstockPhotos-481062550.jpg\",\"keywords\":[\"lavori strani\",\"lavoro\",\"estero\"],\"articleSection\":[\"Ricerca di Lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/lavori-assurdi-la-top-10\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/lavori-assurdi-la-top-10\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/lavori-assurdi-la-top-10\\\/\",\"name\":\"Lavori assurdi: la Top 10 - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/lavori-assurdi-la-top-10\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/lavori-assurdi-la-top-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/ThinkstockPhotos-481062550.jpg\",\"datePublished\":\"2015-07-16T09:23:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/lavori-assurdi-la-top-10\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/lavori-assurdi-la-top-10\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/lavori-assurdi-la-top-10\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/ThinkstockPhotos-481062550.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/ThinkstockPhotos-481062550.jpg\",\"width\":1030,\"height\":687},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/lavori-assurdi-la-top-10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ricerca di Lavoro\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lavori assurdi: la Top 10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/3919aff1269d50f0b11c0a55aad646df\",\"name\":\"Elena Gordini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57441cf144c8cd7818c4ba674f4dad0230acbd714a1c6bc6ac06011d7831d602?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57441cf144c8cd7818c4ba674f4dad0230acbd714a1c6bc6ac06011d7831d602?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57441cf144c8cd7818c4ba674f4dad0230acbd714a1c6bc6ac06011d7831d602?s=96&r=g\",\"caption\":\"Elena Gordini\"},\"description\":\"Traduttrice, blogger e operatrice culturale fra l\u2019Italia e la Spagna.\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/elena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lavori assurdi: la Top 10 - Emagister Blog Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/","og_locale":"it_IT","og_type":"article","og_title":"Lavori assurdi: la Top 10 - Emagister Blog Italia","og_description":"Per trovare un lavoro ci vuole una buona preparazione, corsi adeguati, magari dei master o dei corsi professionali. Poi una ricerca fatta per bene, la lettera di presentazione adeguata e il curriculum giusto, una buona preparazione per affrontare il colloquio di lavoro, l&#8217;atteggiamento giusto e, inultile dirlo, quel pizzico di fortuna che non guasta mai.","og_url":"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2015-07-16T09:23:16+00:00","og_image":[{"width":1030,"height":687,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2015\/07\/ThinkstockPhotos-481062550.jpg","type":"image\/jpeg"}],"author":"Elena Gordini","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Elena Gordini","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/"},"author":{"name":"Elena Gordini","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/3919aff1269d50f0b11c0a55aad646df"},"headline":"Lavori assurdi: la Top 10","datePublished":"2015-07-16T09:23:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/"},"wordCount":700,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2015\/07\/ThinkstockPhotos-481062550.jpg","keywords":["lavori strani","lavoro","estero"],"articleSection":["Ricerca di Lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/","url":"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/","name":"Lavori assurdi: la Top 10 - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2015\/07\/ThinkstockPhotos-481062550.jpg","datePublished":"2015-07-16T09:23:16+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2015\/07\/ThinkstockPhotos-481062550.jpg","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2015\/07\/ThinkstockPhotos-481062550.jpg","width":1030,"height":687},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/lavori-assurdi-la-top-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"Ricerca di Lavoro","item":"https:\/\/www.emagister.it\/blog\/category\/lavoro\/"},{"@type":"ListItem","position":3,"name":"Lavori assurdi: la Top 10"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/3919aff1269d50f0b11c0a55aad646df","name":"Elena Gordini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/57441cf144c8cd7818c4ba674f4dad0230acbd714a1c6bc6ac06011d7831d602?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57441cf144c8cd7818c4ba674f4dad0230acbd714a1c6bc6ac06011d7831d602?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57441cf144c8cd7818c4ba674f4dad0230acbd714a1c6bc6ac06011d7831d602?s=96&r=g","caption":"Elena Gordini"},"description":"Traduttrice, blogger e operatrice culturale fra l\u2019Italia e la Spagna.","url":"https:\/\/www.emagister.it\/blog\/author\/elena\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=842"}],"version-history":[{"count":5,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/842\/revisions"}],"predecessor-version":[{"id":1080,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/842\/revisions\/1080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/1077"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}