{"id":8539,"date":"2021-08-25T07:05:06","date_gmt":"2021-08-25T07:05:06","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=8539"},"modified":"2021-08-30T07:22:39","modified_gmt":"2021-08-30T07:22:39","slug":"metodologie-agili-le-piu-ricercate-dalle-aziende","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/","title":{"rendered":"Metodologie Agili: le pi\u00f9 ricercate dalle aziende"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Sai cosa sono le <\/span><b>Metodologie Agili<\/b><span style=\"font-weight: 400;\">?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Conosciute anche con l\u2019espressione \u201c<\/span><b>sviluppo agile del software<\/b><span style=\"font-weight: 400;\">\u201d, si riferiscono ad un insieme di metodi di sviluppo del software, emersi nei primi anni del 2000 e fondati su principi comuni derivanti dal \u201c<\/span><b>Manifesto per lo sviluppo agile del software<\/b><span style=\"font-weight: 400;\">\u201d conosciuto come \u201c<\/span><b>Manifesto Agile<\/b><span style=\"font-weight: 400;\">\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Anche se l\u2019espressione fa intendere altro, questa metodologia non prevede regole da rispettare in maniera categorica nell\u2019ambito dello sviluppo software. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Nella pratica le metodologie agili permettono di rilasciare modifiche al software con l\u2019obiettivo di <\/span><b>migliorare la soddisfazione dei clienti<\/b><span style=\"font-weight: 400;\">, utilizzano approcci flessibili e lavoro di gruppo, indispensabili per concentrarsi e migliorarsi.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L\u2019introduzione delle metodologie agili all\u2019interno delle aziende ha permesso ai team di lavoro composti da pochi sviluppatori di organizzarsi in maniera pi\u00f9 autonoma e rapida.<\/span><\/p>\n<h2><b>Princ\u00ecpi del Manifesto Agile<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">La metodologia agile si basa su 4 valori e 12 princ\u00ecpi che ritroviamo all\u2019interno del Manifesto Agile, nello specifico:<\/span><\/p>\n<ul>\n<li><b>componente umana:<\/b><span style=\"font-weight: 400;\"> in questo caso specifico ci\u00f2 che conta \u00e8 il confronto di persona e non via mail; questo non \u00e8 solo un principio filosofico ma \u00e8 un mezzo attraverso il quale ottenere risultati notevoli;\u00a0<\/span><\/li>\n<li><b>pianificazione: <span style=\"font-weight: 400;\">elemento fondamentale per lo sviluppo software, questa metodologia permette di eseguire cambiamenti in modo agile e veloce;<\/span><\/b><\/li>\n<li>collaborazione diretta: <span style=\"font-weight: 400;\">\u00e8 possibile raggiungere il risultato desiderato in modo rapido adattando il programma alle esigenze del cliente;<\/span><\/li>\n<li>software funzionante: <span style=\"font-weight: 400;\">l\u2019obiettivo finale \u00e8 avere una documentazione esaustiva del progetto e un prodotto finito e utilizzabile.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Lo scopo delle metodologie agili \u00e8 chiaro: ottenere un prodotto valido ottimizzando tempo e costi,<b><a href=\"emagister.it\/corsi_aulab_hackademy-cen-106978.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-8031 size-full\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/05\/Aulab-Hackademy.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/b> andando incontro alle esigenze del cliente. Per questo motivo lo studio e l\u2019applicazione delle metodologie agili \u00e8 stato introdotto nel corso Hackademy di aulab, durante il quale gli studenti imparano ad utilizzare il <\/span><b>framework SCRUM<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Oltre a questo, durante i <\/span><b>3 mesi intensivi<\/b><span style=\"font-weight: 400;\"> di corso Hackademy vengono trattati i seguenti linguaggi: <\/span><b>HTML, CSS, JAVASCRIPT<\/b><span style=\"font-weight: 400;\"> per lo sviluppo frontend e <\/span><b>PHP<\/b><span style=\"font-weight: 400;\"> con framework <\/span><b>Laravel<\/b><span style=\"font-weight: 400;\"> per lo sviluppo backend.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">All\u2019interno dell\u2019<\/span><b>aula virtuale<\/b><span style=\"font-weight: 400;\"> \u00e8 possibile <\/span><b>confrontarsi con i<\/b> <b>docenti<\/b><span style=\"font-weight: 400;\"> ed <\/span><b>interagire con i compagni<\/b><span style=\"font-weight: 400;\"> di corso. Tutti i materiali sono <\/span><b>disponibili on-demand<\/b><span style=\"font-weight: 400;\"> in modo da poter <\/span><b>rivedere o recuperare le lezioni<\/b><span style=\"font-weight: 400;\"> e <\/span><b>approfondire degli argomenti<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Grazie al metodo strutturato del corso Hackademy \u00e8 inoltre possibile imparare a programmare scrivendo <\/span><b>codice in diretta<\/b><span style=\"font-weight: 400;\">, collaborare in team ed utilizzare i <\/span><b>metodi di lavoro<\/b><span style=\"font-weight: 400;\"> pi\u00f9 richiesti dalle aziende.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se anche tu cerchi una <\/span><b>svolta per la tua carriera<\/b><span style=\"font-weight: 400;\"> oppure desideri <\/span><b>dare una direzione<\/b><span style=\"font-weight: 400;\"> alla tua passione per l\u2019informatica, <\/span><b>iscriviti al prossimo corso<\/b><span style=\"font-weight: 400;\">! Scopri di pi\u00f9 su <\/span><b>aulab.it<\/b>.<\/p>\n<p><span style=\"font-weight: 400;\">Sei interessato a ricevere maggiori informazioni sui progetti\u00a0 promossi da\u00a0<strong>Aulab Hackademy<\/strong>? Mettiti in\u00a0<a href=\"https:\/\/www.emagister.it\/contact\/student\" target=\"_blank\" rel=\"noopener\">contatto<\/a>\u00a0con lo staff Emagister, sarai ricontattato da un nostro operatore che ti illustrer\u00e0 tutta l\u2019offerta formativa disponibile!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sai cosa sono le Metodologie Agili? Conosciute anche con l\u2019espressione \u201csviluppo agile del software\u201d, si riferiscono ad un insieme di metodi di sviluppo del software, emersi nei primi anni del 2000 e fondati su principi comuni derivanti dal \u201cManifesto per lo sviluppo agile del software\u201d conosciuto come \u201cManifesto Agile\u201d. Anche se l\u2019espressione fa intendere altro, [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":8543,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[867,1136,1137,260,592],"class_list":["post-8539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-clienti","tag-noticiasskuola","tag-1136","tag-aulab-hackademy","tag-centri-di-formazione","tag-centri-emagister"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Metodologie Agili: le pi\u00f9 ricercate dalle aziende - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Metodologie Agili: le pi\u00f9 ricercate dalle aziende - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"Sai cosa sono le Metodologie Agili? Conosciute anche con l\u2019espressione \u201csviluppo agile del software\u201d, si riferiscono ad un insieme di metodi di sviluppo del software, emersi nei primi anni del 2000 e fondati su principi comuni derivanti dal \u201cManifesto per lo sviluppo agile del software\u201d conosciuto come \u201cManifesto Agile\u201d. Anche se l\u2019espressione fa intendere altro, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-25T07:05:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-30T07:22:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/08\/Metodologie-Agili-le-pi\u00f9-ricercate-dalle-aziende.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1156\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/metodologie-agili-le-piu-ricercate-dalle-aziende\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/metodologie-agili-le-piu-ricercate-dalle-aziende\\\/\"},\"author\":{\"name\":\"Redazione Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\"},\"headline\":\"Metodologie Agili: le pi\u00f9 ricercate dalle aziende\",\"datePublished\":\"2021-08-25T07:05:06+00:00\",\"dateModified\":\"2021-08-30T07:22:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/metodologie-agili-le-piu-ricercate-dalle-aziende\\\/\"},\"wordCount\":454,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/metodologie-agili-le-piu-ricercate-dalle-aziende\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Metodologie-Agili-le-pi\u00f9-ricercate-dalle-aziende.jpg\",\"keywords\":[\"noticiasSkuola\",\"99992269674249392522766775093402\",\"Aulab Hackademy\",\"Centri di Formazione\",\"centri emagister\"],\"articleSection\":[\"I Nostri Clienti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/metodologie-agili-le-piu-ricercate-dalle-aziende\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/metodologie-agili-le-piu-ricercate-dalle-aziende\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/metodologie-agili-le-piu-ricercate-dalle-aziende\\\/\",\"name\":\"Metodologie Agili: le pi\u00f9 ricercate dalle aziende - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/metodologie-agili-le-piu-ricercate-dalle-aziende\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/metodologie-agili-le-piu-ricercate-dalle-aziende\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Metodologie-Agili-le-pi\u00f9-ricercate-dalle-aziende.jpg\",\"datePublished\":\"2021-08-25T07:05:06+00:00\",\"dateModified\":\"2021-08-30T07:22:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/metodologie-agili-le-piu-ricercate-dalle-aziende\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/metodologie-agili-le-piu-ricercate-dalle-aziende\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/metodologie-agili-le-piu-ricercate-dalle-aziende\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Metodologie-Agili-le-pi\u00f9-ricercate-dalle-aziende.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Metodologie-Agili-le-pi\u00f9-ricercate-dalle-aziende.jpg\",\"width\":1920,\"height\":1156,\"caption\":\"Agile concept with young man in the night\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/metodologie-agili-le-piu-ricercate-dalle-aziende\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Nostri Clienti\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/i-nostri-clienti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Metodologie Agili: le pi\u00f9 ricercate dalle aziende\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\",\"name\":\"Redazione Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Redazione Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/redazione-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Metodologie Agili: le pi\u00f9 ricercate dalle aziende - Emagister Blog Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/","og_locale":"it_IT","og_type":"article","og_title":"Metodologie Agili: le pi\u00f9 ricercate dalle aziende - Emagister Blog Italia","og_description":"Sai cosa sono le Metodologie Agili? Conosciute anche con l\u2019espressione \u201csviluppo agile del software\u201d, si riferiscono ad un insieme di metodi di sviluppo del software, emersi nei primi anni del 2000 e fondati su principi comuni derivanti dal \u201cManifesto per lo sviluppo agile del software\u201d conosciuto come \u201cManifesto Agile\u201d. Anche se l\u2019espressione fa intendere altro, [&hellip;]","og_url":"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2021-08-25T07:05:06+00:00","article_modified_time":"2021-08-30T07:22:39+00:00","og_image":[{"width":1920,"height":1156,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/08\/Metodologie-Agili-le-pi\u00f9-ricercate-dalle-aziende.jpg","type":"image\/jpeg"}],"author":"Redazione Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Redazione Emagister","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/"},"author":{"name":"Redazione Emagister","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897"},"headline":"Metodologie Agili: le pi\u00f9 ricercate dalle aziende","datePublished":"2021-08-25T07:05:06+00:00","dateModified":"2021-08-30T07:22:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/"},"wordCount":454,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/08\/Metodologie-Agili-le-pi\u00f9-ricercate-dalle-aziende.jpg","keywords":["noticiasSkuola","99992269674249392522766775093402","Aulab Hackademy","Centri di Formazione","centri emagister"],"articleSection":["I Nostri Clienti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/","url":"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/","name":"Metodologie Agili: le pi\u00f9 ricercate dalle aziende - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/08\/Metodologie-Agili-le-pi\u00f9-ricercate-dalle-aziende.jpg","datePublished":"2021-08-25T07:05:06+00:00","dateModified":"2021-08-30T07:22:39+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/08\/Metodologie-Agili-le-pi\u00f9-ricercate-dalle-aziende.jpg","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2021\/08\/Metodologie-Agili-le-pi\u00f9-ricercate-dalle-aziende.jpg","width":1920,"height":1156,"caption":"Agile concept with young man in the night"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/metodologie-agili-le-piu-ricercate-dalle-aziende\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"I Nostri Clienti","item":"https:\/\/www.emagister.it\/blog\/category\/i-nostri-clienti\/"},{"@type":"ListItem","position":3,"name":"Metodologie Agili: le pi\u00f9 ricercate dalle aziende"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897","name":"Redazione Emagister","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Redazione Emagister"},"url":"https:\/\/www.emagister.it\/blog\/author\/redazione-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/8539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=8539"}],"version-history":[{"count":2,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/8539\/revisions"}],"predecessor-version":[{"id":8552,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/8539\/revisions\/8552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/8543"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=8539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=8539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=8539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}