{"id":9496,"date":"2022-01-14T08:08:22","date_gmt":"2022-01-14T08:08:22","guid":{"rendered":"https:\/\/www.emagister.it\/blog\/?p=9496"},"modified":"2022-01-17T09:01:05","modified_gmt":"2022-01-17T09:01:05","slug":"la-psicologia-dei-colori-e-il-benessere","status":"publish","type":"post","link":"https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/","title":{"rendered":"La psicologia dei colori e il benessere"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Gli esseri umani cerchiamo di sentirci comodi con l\u2019ambiente che ci circonda. Per riuscire a farlo, cambiamo il nostro intorno in diversi modi. Tra i vari approcci che esistono per ottenere questo comfort, troviamo <strong>l\u2019uso dei colori<\/strong>. \u00c8 per questo che usiamo per sentirci meglio la <\/span><b>psicologia dei colori<\/b><span style=\"font-weight: 400;\">, un tipo di medicina alternativa e olistica non invasiva. Dai un\u2019occhiata alla nostra <\/span><span style=\"font-weight: 400;\">Certificazione Esperto in Psicologia Olistica<\/span><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<h2><b>Cos\u2019\u00e8 la psicologia dei colori?<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">La<strong> psicologia dei colori<\/strong>, anche definita come cromoterapia, si basa nell\u2019uso dei colori a vantaggio del <strong>benessere fisico ed emotivo<\/strong> degli individui. Questo \u00e8 possibile grazie alle capacit\u00e0 che hanno questi di rilassare o stimolare.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questa branca della psicologia olistica si basa nella <strong>medicina ayurvedica<\/strong> che si basa nella comprensione stessa dell\u2019essere umano in armonia con la natura. Per questo motivo si considera che l\u2019equilibrio tra uomo e ambiente significa salute, mentre lo squilibrio indica la malattia. Secondo questa disciplina, il corpo \u00e8 attraversato da sette punti energetici definiti <\/span><i><span style=\"font-weight: 400;\">chakra<\/span><\/i><span style=\"font-weight: 400;\"> e da energia vitale definita <\/span><i><span style=\"font-weight: 400;\">prana<\/span><\/i><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<h2><b>Come usare i colori<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Sentimenti come ansia, stress o tristezza fanno accumulare tensioni in alcune zone del corpo, producendo cos\u00ec malessere. L\u2019uso corretto della psicologia dei colori aiuta a <strong>liberare queste tensioni<\/strong>, permettendo l\u2019armonia del corpo e della mente.\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.emagister.it\/corsi_elbs-cen-106586.htm\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-9503 size-full\" src=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/01\/m-14.png\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">I principali colori che si studiano nella psicologia dei colori sono <strong>sette<\/strong>, come i <em>chakra<\/em> nel corpo, e questi vanno associati. Bisogna quindi sapere in base alla dolenza o malessere, che colore usare per stimolare il <em>chakra<\/em> adeguato.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">I <strong>colori caldi<\/strong> rappresentano i <strong><em>chakra<\/em>\u00a0pi\u00f9 bassi<\/strong> e possono suscitare emozioni molto diverse, dalla gioia e la forza fino ad aggressivit\u00e0 o ansia. I <strong>colori freddi<\/strong> sono associati ai <strong><em>chakra<\/em> pi\u00f9 alti<\/strong> e corrispondono con sensazioni di calma e meditazione, ma anche con stanchezza o tristezza.<\/span><\/p>\n<h2><b>Propriet\u00e0 e benefici dei colori<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Vediamo ora pi\u00f9 dettagliatamente ogni colore e i benefici che pu\u00f2 apportare.\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Rosso<\/strong>: senza dubbio uno dei colori pi\u00f9 potenti, che rappresenta <strong>la forza, la salute, la vitalit\u00e0 e l\u2019energia<\/strong>. Permette di stimolare l\u2019attivit\u00e0 mentale, motivo per cui bisogna utilizzarlo con attenzione per evitare un effetto di iperattivit\u00e0.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Blu<\/strong>: un colore calmante, che favorisce <strong>la concentrazione, la conoscenza e la comunicazione<\/strong>. Permette anche di migliorare la qualit\u00e0 del sonno in quanto armonizza la mente.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Indaco<\/strong>: anch\u2019esso considerato un colore che apporta <strong>calma<\/strong>, si considera sedativo e migliora l\u2019intuizione.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Verde<\/strong>: il colore della natura per eccellenza, favorisce la<strong> serenit\u00e0<\/strong>. Indica la speranza e la pace. Permette di raggiungere uno stato di quiete e equilibrio armonico.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Giallo<\/strong>: associato <strong>alla gioia e alla felicit\u00e0<\/strong>, permette di stimolare l\u2019apprendimento. \u00c8 un colore che fornisce allegria perch\u00e9 esorta i sensi.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Arancione<\/strong>: ha un\u2019azione liberatoria, di piacere dei sensi, motivo per cui si associa alla <strong>stimolazione sessuale<\/strong>. Dona ottimismo e favorisce il piacere in generale.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Viola<\/strong>: il colore della <strong>meditazione<\/strong>. Calma il sistema nervoso, favorendo cos\u00ec il rilassamento muscolare e il risveglio spirituale. Migliora la concentrazione e l\u2019ottimismo e favorisce una visione chiara dell\u2019ambiente emotivo circostante.\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Come abbiamo indicato, ogni colore offre i suoi pro e i suoi contra, per cui dipendendo dal tipo di malessere dell\u2019individuo, bisogner\u00e0 utilizzare un colore o un altro. Questi colori possono essere combinati dipendendo dalla dolenza e si possono usare in diversi modi. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli esseri umani cerchiamo di sentirci comodi con l\u2019ambiente che ci circonda. Per riuscire a farlo, cambiamo il nostro intorno in diversi modi. Tra i vari approcci che esistono per ottenere questo comfort, troviamo l\u2019uso dei colori. \u00c8 per questo che usiamo per sentirci meglio la psicologia dei colori, un tipo di medicina alternativa e [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":9497,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[260,592,1181,1182,1183],"class_list":["post-9496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-nostri-clienti","tag-centri-di-formazione","tag-centri-emagister","tag-elbs","tag-1182","tag-ij_sector_center_99992269674249392522766775093010_138"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La psicologia dei colori e il benessere - Emagister Blog Italia<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La psicologia dei colori e il benessere - Emagister Blog Italia\" \/>\n<meta property=\"og:description\" content=\"Gli esseri umani cerchiamo di sentirci comodi con l\u2019ambiente che ci circonda. Per riuscire a farlo, cambiamo il nostro intorno in diversi modi. Tra i vari approcci che esistono per ottenere questo comfort, troviamo l\u2019uso dei colori. \u00c8 per questo che usiamo per sentirci meglio la psicologia dei colori, un tipo di medicina alternativa e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/\" \/>\n<meta property=\"og:site_name\" content=\"Emagister Blog Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Emagister.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-14T08:08:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-17T09:01:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/01\/GettyImages-1185382671.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1915\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:site\" content=\"@emagister_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-psicologia-dei-colori-e-il-benessere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-psicologia-dei-colori-e-il-benessere\\\/\"},\"author\":{\"name\":\"Redazione Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\"},\"headline\":\"La psicologia dei colori e il benessere\",\"datePublished\":\"2022-01-14T08:08:22+00:00\",\"dateModified\":\"2022-01-17T09:01:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-psicologia-dei-colori-e-il-benessere\\\/\"},\"wordCount\":550,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-psicologia-dei-colori-e-il-benessere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/GettyImages-1185382671.jpg\",\"keywords\":[\"Centri di Formazione\",\"centri emagister\",\"ELBS\",\"99992269674249392522766775093010\",\"ij_sector_center_99992269674249392522766775093010_138\"],\"articleSection\":[\"I Nostri Clienti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-psicologia-dei-colori-e-il-benessere\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-psicologia-dei-colori-e-il-benessere\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-psicologia-dei-colori-e-il-benessere\\\/\",\"name\":\"La psicologia dei colori e il benessere - Emagister Blog Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-psicologia-dei-colori-e-il-benessere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-psicologia-dei-colori-e-il-benessere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/GettyImages-1185382671.jpg\",\"datePublished\":\"2022-01-14T08:08:22+00:00\",\"dateModified\":\"2022-01-17T09:01:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-psicologia-dei-colori-e-il-benessere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-psicologia-dei-colori-e-il-benessere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-psicologia-dei-colori-e-il-benessere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/GettyImages-1185382671.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/GettyImages-1185382671.jpg\",\"width\":1915,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/la-psicologia-dei-colori-e-il-benessere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ue821\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Nostri Clienti\",\"item\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/category\\\/i-nostri-clienti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La psicologia dei colori e il benessere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"name\":\"Emagister Blog Italia\",\"description\":\"Notizie e curiosit\u00e0 sul mondo della formazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#organization\",\"name\":\"Emagister Italia\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Emagister.Italia\\\/\",\"https:\\\/\\\/x.com\\\/emagister_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/#\\\/schema\\\/person\\\/b854365c040bf8645900cd60a97f1897\",\"name\":\"Redazione Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Redazione Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.it\\\/blog\\\/author\\\/redazione-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La psicologia dei colori e il benessere - Emagister Blog Italia","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"La psicologia dei colori e il benessere - Emagister Blog Italia","og_description":"Gli esseri umani cerchiamo di sentirci comodi con l\u2019ambiente che ci circonda. Per riuscire a farlo, cambiamo il nostro intorno in diversi modi. Tra i vari approcci che esistono per ottenere questo comfort, troviamo l\u2019uso dei colori. \u00c8 per questo che usiamo per sentirci meglio la psicologia dei colori, un tipo di medicina alternativa e [&hellip;]","og_url":"https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/","og_site_name":"Emagister Blog Italia","article_publisher":"https:\/\/es-la.facebook.com\/Emagister.Italia\/","article_published_time":"2022-01-14T08:08:22+00:00","article_modified_time":"2022-01-17T09:01:05+00:00","og_image":[{"width":1915,"height":1280,"url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/01\/GettyImages-1185382671.jpg","type":"image\/jpeg"}],"author":"Redazione Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister_it","twitter_site":"@emagister_it","twitter_misc":{"Scritto da":"Redazione Emagister","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/#article","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/"},"author":{"name":"Redazione Emagister","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897"},"headline":"La psicologia dei colori e il benessere","datePublished":"2022-01-14T08:08:22+00:00","dateModified":"2022-01-17T09:01:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/"},"wordCount":550,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/01\/GettyImages-1185382671.jpg","keywords":["Centri di Formazione","centri emagister","ELBS","99992269674249392522766775093010","ij_sector_center_99992269674249392522766775093010_138"],"articleSection":["I Nostri Clienti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/","url":"https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/","name":"La psicologia dei colori e il benessere - Emagister Blog Italia","isPartOf":{"@id":"https:\/\/www.emagister.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/01\/GettyImages-1185382671.jpg","datePublished":"2022-01-14T08:08:22+00:00","dateModified":"2022-01-17T09:01:05+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/#primaryimage","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/01\/GettyImages-1185382671.jpg","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2022\/01\/GettyImages-1185382671.jpg","width":1915,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.it\/blog\/la-psicologia-dei-colori-e-il-benessere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ue821","item":"https:\/\/www.emagister.it\/blog\/homepage\/"},{"@type":"ListItem","position":2,"name":"I Nostri Clienti","item":"https:\/\/www.emagister.it\/blog\/category\/i-nostri-clienti\/"},{"@type":"ListItem","position":3,"name":"La psicologia dei colori e il benessere"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.it\/blog\/#website","url":"https:\/\/www.emagister.it\/blog\/","name":"Emagister Blog Italia","description":"Notizie e curiosit\u00e0 sul mondo della formazione","publisher":{"@id":"https:\/\/www.emagister.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emagister.it\/blog\/#organization","name":"Emagister Italia","url":"https:\/\/www.emagister.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","contentUrl":"https:\/\/www.emagister.it\/blog\/wp-content\/uploads\/2018\/07\/photo.png","width":120,"height":120,"caption":"Emagister Italia"},"image":{"@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Emagister.Italia\/","https:\/\/x.com\/emagister_it"]},{"@type":"Person","@id":"https:\/\/www.emagister.it\/blog\/#\/schema\/person\/b854365c040bf8645900cd60a97f1897","name":"Redazione Emagister","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Redazione Emagister"},"url":"https:\/\/www.emagister.it\/blog\/author\/redazione-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/9496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/comments?post=9496"}],"version-history":[{"count":4,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/9496\/revisions"}],"predecessor-version":[{"id":9877,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/posts\/9496\/revisions\/9877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media\/9497"}],"wp:attachment":[{"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/media?parent=9496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/categories?post=9496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.it\/blog\/wp-json\/wp\/v2\/tags?post=9496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}